{"id":3436,"date":"2020-07-04T22:10:53","date_gmt":"2020-07-05T03:10:53","guid":{"rendered":"https:\/\/acoredu.graphich.agency\/?p=3436"},"modified":"2020-07-06T08:23:45","modified_gmt":"2020-07-06T13:23:45","slug":"whats-new-in-liver-imaging-july-2020-italian","status":"publish","type":"post","link":"https:\/\/acoredu.graphich.agency\/it\/whats-new-in-liver-imaging-july-2020-italian\/","title":{"rendered":"Novit\u00e0 nell&#8217;imaging epatico?"},"content":{"rendered":"<p>&nbsp;<\/p>\n<h3><span style=\"color: #800080;\"><strong>Liver CT Imaging<\/strong><\/span><\/h3>\n<p>&nbsp;<\/p>\n<h5><span style=\"color: #3366ff;\"><strong>Variability of quantitative measurements of metastatic liver lesions: a multi-radiation-dose-level and multi-reader comparison<\/strong><\/span><\/h5>\n<p>Ding Y, Marin D, Vernuccio F, Gonzalez F, Williamson H V., Becker H-C, et al. Variability of quantitative measurements of metastatic liver lesions: a multi-radiation-dose-level and multi-reader comparison. Abdom Radiol [Internet]. 2020 Jun 10 [cited 2020 Jun 17];1\u201311. Available from: <a href=\"https:\/\/link.springer.com\/article\/10.1007\/s00261-020-02601-8\">https:\/\/link.springer.com\/article\/10.1007\/s00261-020-02601-8<\/a><\/p>\n<p><strong>Parole chiave<\/strong>: TC, dose di radiazioni, qualit\u00e0 dell&#8217;immagine, metastasi al fegato, stadiazione.<\/p>\n<p><strong>Quesito clinico<\/strong>: se le scansioni TC vengono eseguite con dosi di radiazioni basse per evitare radiazioni eccessive ai pazienti che hanno gi\u00e0 diagnosi di cancro, questo pu\u00f2 ridurre la qualit\u00e0 dell&#8217;esame di stadiazione o eventualmente impedire un&#8217;interpretazione accurata?<\/p>\n<p><strong>Cosa \u00e8 stato fatto<\/strong>: la variabilit\u00e0 delle misurazioni del tumore dovuta alla variabilit\u00e0 della dose di radiazioni e a quella interosservatore (manuale vs semiautomatica) \u00e8 stata studiata negli esami di stadiazione di 23 pazienti (39 con lesioni metastatiche al fegato).<\/p>\n<p><strong>Come \u00e8 stato fatto<\/strong>: tutti i pazienti sono stati sottoposti ad esame TC di stadiazione usando una TC a doppia sorgente, a singola energia, con mezzo di contrasto. Le immagini TC sono state ricostruite con sette diversi livelli di dose di radiazioni, valutati da quattro radiologi manualmente e da due radiologi in modo semi-automatico.<\/p>\n<p><strong>Risultati<\/strong>: la dimensione del tumore \u00e8 stata sovrastimata se valutata manualmente rispetto alla valutazione semiautomatica. Tra quelli valutati semi-automaticamente, i tumori sono stati sovradimensionati nelle immagini ricostruite a dosi di radiazioni &lt;50% della dose originale. La variabilit\u00e0 complessiva della misurazione correlata alla dose di radiazioni non era significativamente diversa dalla variabilit\u00e0 inter\/intraosservatore.<\/p>\n<p><strong>Conclusioni<\/strong>: una riduzione del livello di dose di radiazione &lt;50% rispetto al protocollo TC convenzionale pu\u00f2 compromettere la qualit\u00e0 dell&#8217;esame di stadiazione.<\/p>\n<p><strong>Implicazioni<\/strong>: le strutture che seguono i protocolli per ridurre il livello della dose di radiazioni negli gli esami di stadiazione del tumore possono andare incontro a sovradimensionamento di eventuali lesioni metastatiche nel fegato.<\/p>\n<p>&nbsp;<\/p>\n<h5><span style=\"color: #3366ff;\"><strong>Double Low-Dose Dual-Energy Liver CT in Patients at High-Risk of HCC\u00a0<\/strong><strong>A Prospective, Randomized, Single-Center Study<\/strong><\/span><\/h5>\n<p>Yoon JH, Chang W, Lee ES, Lee SM, Lee JM. Double Low-Dose Dual-Energy Liver CT in Patients at High-Risk of HCC. Invest Radiol [Internet]. 2020 Jun 1 [cited 2020 Jun 17];55(6):340\u20138. Available from: <a href=\"http:\/\/journals.lww.com\/10.1097\/RLI.0000000000000643\">http:\/\/journals.lww.com\/10.1097\/RLI.0000000000000643<\/a><\/p>\n<p><strong>Parole chiave<\/strong>: TC, dose di radiazioni, qualit\u00e0 dell&#8217;immagine, rapporto contrasto-rumore, HCC.<\/p>\n<p><strong>Quesito clinico<\/strong>: un maggiore contrasto migliora la qualit\u00e0 dell&#8217;immagine, ma un aumento del rumore ne ostacola altri aspetti. Sebbene la riduzione della dose di radiazioni (abbassamento del kiloelettronvolt, keV) aumenti il rapporto contrasto-rumore, \u00e8 noto che aumenta anche il rumore complessivo nei pazienti con un indice di massa corporea elevato (BMI). Nei pazienti ad alto rischio di carcinoma epatocellulare (HCC), la TC a doppia bassa dose (riduzione della dose di radiazioni, riduzione della dose media di contrasto endovenoso) pu\u00f2 influenzare la valutazione clinica?<\/p>\n<p><strong>Cosa \u00e8 stato fatto<\/strong>: i pazienti con BMI basso ad alto rischio di carcinoma epatocellulare sono stati sottoposti a TC con dose standard e ad esame TC a doppia basse dose. Le immagini TC sono state confrontate in termini di rumore e contrasto dell\u2019immagine, qualitativamente e quantitativamente, nonch\u00e9 per la visibilit\u00e0 e il rilevamento della lesione.<\/p>\n<p><strong>Come \u00e8 stato fatto<\/strong>: in questo studio in doppio cieco, 67 pazienti con BMI basso ad alto rischio per HCC sono stati divisi in due gruppi: un gruppo \u00e8 stato sottoposto a imaging a dose standard seguito da ricostruzione ibrida iterativa delle immagini TC (iDose), mentre un secondo gruppo ha subito una dose di radiazioni (50 keV) e di contrasto ridotte.<\/p>\n<p><strong>Risultati<\/strong>: la percettibilit\u00e0 della lesione era significativamente pi\u00f9 alta nel gruppo a doppia bassa dose rispetto al gruppo iDose, ma non vi era alcuna differenza significativa nel rilevamento della lesione. Sebbene non vi sia stata una differenza significativa nel rumore dell&#8217;immagine in termini quantitativi tra i due gruppi, il rapporto contrasto-rumore \u00e8 risultato maggiore nel gruppo a doppia bassa dose.<\/p>\n<p><strong>Conclusioni<\/strong>: la TC a doppia bassa dose non modifica in modo significativo il rilevamento della lesione o il rumore dell&#8217;immagine nei pazienti con BMI basso ad alto rischio di HCC, e in effetti aumenta la visibilit\u00e0 della lesione e il rapporto contrasto-rumore.<\/p>\n<p><strong>Implicazioni<\/strong>: i pazienti con BMI basso possono essere presi in considerazione per esami TC di sorveglianza per HCC, a doppia bassa dose, poich\u00e9 non sono intrinsecamente soggetti ad un aumento del rumore nel contesto di una riduzione della dose di radiazioni.<\/p>\n<p>&nbsp;<\/p>\n<h3><span style=\"color: #800080;\"><strong>Liver US Imaging<\/strong><\/span><\/h3>\n<p>&nbsp;<\/p>\n<h5><span style=\"color: #3366ff;\"><strong>Diagnostic value of contrast-enhanced ultrasound versus computed tomography for hepatocellular carcinoma: a retrospective, single-center evaluation of 234 patients<\/strong><\/span><\/h5>\n<p>Schwarze V, Marschner C, V\u00f6lckers W, Grosu S, Negr\u00e3o de Figueiredo G, R\u00fcbenthaler J, et al. Diagnostic value of contrast-enhanced ultrasound versus computed tomography for hepatocellular carcinoma: a retrospective, single-center evaluation of 234 patients. J Int Med Res [Internet]. 2020 Jun 12 [cited 2020 Jun 17];48(6):030006052093015. Available from:<\/p>\n<p><a href=\"http:\/\/journals.sagepub.com\/doi\/10.1177\/0300060520930151\">http:\/\/journals.sagepub.com\/doi\/10.1177\/0300060520930151<\/a><\/p>\n<p><strong>Parole chiave<\/strong>: TC, CEUS, valore diagnostico, HCC.<\/p>\n<p><strong>Quesito clinico<\/strong>: la valutazione dell&#8217;HCC si basa sui risultati di diverse modalit\u00e0 di imaging, tra queste l\u2019ecografia con mezzo di contrasto (CEUS) consente una valutazione dinamica della perfusione della lesione epatica. In che modo il valore diagnostico della CEUS per l\u2019HCC nel fegato \u00e8 comparabile con l\u2019esame TC?<\/p>\n<p><strong>Cosa \u00e8 stato fatto e come<\/strong>: in 234 pazienti con lesioni epatiche sospette valutati in un periodo di 15 anni e sottoposti sia a CEUS che a TC, le due tecniche sono state valutate comparativamente per il valore diagnostico dell&#8217;HCC.<\/p>\n<p><strong>Risultati e risultati<\/strong>: i risultati hanno mostrato che la CEUS aveva una sensibilit\u00e0 del 94%, una specificit\u00e0 del 70%, VPP del 93% e VPN del 72% per la diagnosi di HCC, quando si utilizzava l\u2019esame TC come gold standard.<\/p>\n<p><strong>Conclusione<\/strong>: gli autori hanno concluso che la CEUS \u00e8 una metodica sicura e ha un&#8217;elevata precisione diagnostica nella valutazione dell&#8217;HCC.<\/p>\n<p><strong>Implicazioni<\/strong>: se una struttura ha le competenze per eseguire la CEUS, e si desidera avere ulteriori informazioni sulla perfusione della lesione epatica, si pu\u00f2 essere certi dell&#8217;elevata accuratezza diagnostica di questa tecnica per la valutazione dell\u2019HCC.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<h5><span style=\"color: #3366ff;\"><strong>Novel Method for Ultrasound<\/strong><strong>\u2010<\/strong><strong>Derived Fat Fraction Using an Integrated Phantom<\/strong><\/span><\/h5>\n<p>Labyed Y, Milkowski A. Novel Method for Ultrasound\u2010Derived Fat Fraction Using an Integrated Phantom. J Ultrasound Med [Internet]. 2020 Jun 11 [cited 2020 Jun 17];jum.15364. Available from: <a href=\"https:\/\/onlinelibrary.wiley.com\/doi\/abs\/10.1002\/jum.15364\">https:\/\/onlinelibrary.wiley.com\/doi\/abs\/10.1002\/jum.15364<\/a><\/p>\n<p><strong>Parole chiave<\/strong>: ultrasuoni, NAFLD, biomarcatore quantitativo di imaging, valore diagnostico.<\/p>\n<p><strong>Quesito clinico<\/strong>: la steatosi epatica non analcolica (NAFLD) pu\u00f2 essere diagnosticata con l\u2019esame istopatologico in seguito a biopsia epatica o mediante imaging quantitativo come la PDFF (proton density fat fraction) calcolabile in risonanza magnetica (RM). \u00c8 possibile utilizzare un metodo di riferimento integrato per l&#8217;ecografia quantitativa per produrre un analogo strumento di frazione grassa derivata dagli ultrasuoni (UDFF)?<\/p>\n<p><strong>Cosa \u00e8 stato fatto<\/strong>: i pazienti con NAFLD nota\/sospetta sono stati sottoposti a RM-PDFF con ultrasuoni o biopsia epatica al fine di creare correlazioni e produrre algoritmicamente questo strumento UDFF. Quest\u2019ultimo \u00e8 stato quindi confrontato con i risultati della biopsia epatica e con la RM-PDFF.<\/p>\n<p><strong>Come \u00e8 stato fatto<\/strong>: 101 adulti con NAFLD nota\/sospetta sono stati sottoposti a RM-PDFF e ad ecografia, rispetto a 90 adulti NAFLD sottoposti a biopsia epatica. \u00c8 stata eseguita un\u2019analisi di regressione lineare sulla base dell&#8217;attenuazione e dei coefficienti di retrodiffusione per creare l&#8217;UDFF.<\/p>\n<p><strong>Risultati<\/strong>: l&#8217;UDFF \u00e8 risultato essere quasi equivalente alla RM-PDFF per il rilevamento di NAFLD di grado inferiore. \u00c8 stato osservato che ha prestazioni elevate, ma non cos\u00ec elevate come la RM-PDFF, per il rilevamento di NAFLD di grado superiore.<\/p>\n<p><strong>Conclusione<\/strong>: uno strumento UDFF potrebbe fornire un metodo a basso costo e non invasivo per quantificare la frazione di grasso epatico, poich\u00e9 l&#8217;UDFF possiede una buona correlazione con l\u2019esame istologico o con la RM-PDFF.<\/p>\n<p><strong>Implicazioni<\/strong>: la diagnosi di NAFLD pu\u00f2 essere fatta mediante biopsia epatica (metodica invasiva) o attraverso imaging quantitativo non invasivo. Mentre la RM pu\u00f2 essere utilizzata con il suo strumento PDFF per calcolare la frazione grassa, un analogo strumento UDFF basato sugli ultrasuoni pu\u00f2 fornire un valore diagnostico simile.<\/p>\n<p>&nbsp;<\/p>\n<h5><span style=\"color: #3366ff;\"><strong>Characterization of Indeterminate Liver Lesions on CT and MRI With Contrast-Enhanced Ultrasound: What Is the Evidence?<\/strong><\/span><\/h5>\n<p>Wang DC, Jang H-J, Kim TK. Characterization of Indeterminate Liver Lesions on CT and MRI With Contrast-Enhanced Ultrasound: What Is the Evidence? Am J Roentgenol [Internet]. 2020 Jun 1 [cited 2020 Jun 17];214(6):1295\u2013304. Available from:<\/p>\n<p><a href=\"https:\/\/www.ajronline.org\/doi\/10.2214\/AJR.19.21498\">https:\/\/www.ajronline.org\/doi\/10.2214\/AJR.19.21498<\/a><\/p>\n<p><strong>Parole chiave<\/strong>: CEUS, valore diagnostico.<\/p>\n<p><strong>Quesito clinico<\/strong>: utilizzando la CEUS, i medici radiologi possono visualizzare pattern di enhanement in tempo reale. \u00c8 possibile quindi utilizzare la CEUS come step diagnostico successivo nella valutazione delle lesioni epatiche indeterminate all\u2019esame TC o RM?<\/p>\n<p><strong>Cosa \u00e8 stato fatto<\/strong>: Wang et al forniscono esempi di imaging di quando la CEUS ha rilevato un enhancement in fase arteriosa o la recidiva di HCC post-ablazione. In aggiunta, forniscono esempi di come la CEUS pu\u00f2 distinguere tra HCC e colangiocarcinoma intraepatico, trombi tumorali benigni e maligni, lesioni cistiche benigne e neoplastiche, adenoma e FNH.<\/p>\n<p><strong>Implicazioni<\/strong>: la CEUS pu\u00f2 aiutare come step successivo nella valutazione delle lesioni epatiche che risultano indeterminate alla TC o alla RM, come nelle situazioni sopra menzionate.<\/p>\n<p>&nbsp;<\/p>\n<h3><span style=\"color: #800080;\"><strong>Liver MR Imaging<\/strong><\/span><\/h3>\n<p>&nbsp;<\/p>\n<h5><span style=\"color: #3366ff;\"><strong>Evaluation of Glypican-3 Expression in Hepatocellular Carcinoma by Using IDEAL IQ Magnetic Resonance Imaging<\/strong><\/span><\/h5>\n<p>Chen R, Bai Y, Liu T, et al. Evaluation of Glypican-3 Expression in Hepatocellular Carcinoma by Using IDEAL IQ Magnetic Resonance Imaging. Acad Radiol [Internet]. Elsevier; 2020 [cited 2020]; Available from:<\/p>\n<p><a href=\"https:\/\/linkinghub.elsevier.com\/retrieve\/pii\/S1076633220302919\">https:\/\/linkinghub.elsevier.com\/retrieve\/pii\/S1076633220302919<\/a><\/p>\n<p><strong>Parole chiave<\/strong>: RM, biomarcatore quantitativo di imaging, HCC.<\/p>\n<p><strong>Quesito clinico<\/strong>: Glypican-3 (GPC3) \u00e8 un biomarcatore che pu\u00f2 fungere da marcatore prognostico cos\u00ec come da bersaglio immunoterapeutico per l&#8217;HCC. GPC3 \u00e8 normalmente controllato a partire da campioni di biopsia epatica. L&#8217;AFP \u00e8 un altro noto marcatore prognostico per l&#8217;HCC derivato dal siero sanguigno. La risonanza magnetica (RM) pu\u00f2 prevedere l&#8217;espressione di GPC3 nell&#8217;HCC in modo non invasivo usando solo le caratteristiche di imaging?<\/p>\n<p><strong>Cosa \u00e8 stato fatto<\/strong>: 76 pazienti con diagnosi di HCC basata sull\u2019esame istopatologico sono stati sottoposti a RM con mezzo di contrasto e con un algoritmo chiamato decomposizione iterativa di acqua e grasso con eco-asimmetria e stima dei minimi quadrati (IDEAL IQ) per valutare eventuali marcatori quantitativi di imaging che potrebbero correlare con GPC3.<\/p>\n<p><strong>Come \u00e8 stato fatto<\/strong>: la regione di interesse (ROI) \u00e8 stata disegnata sul tumore di ciascun paziente su sequenze diverse tra cui la mappa della frazione di grasso IDEAL IQ e la rilassometria R2*. Quindi, \u00e8 stato utilizzato un test di Mann-Whitney per confrontare i valori di intensit\u00e0 corrispondenti all&#8217;interno della ROI su ciascuna sequenza. \u00c8 stata eseguita un\u2019analisi ROC.<\/p>\n<p><strong>Risultati<\/strong>: valori di intensit\u00e0 per il tumore sulla sequenza di rilassometria R2* sono correlati con l&#8217;espressione GPC3, con una sensibilit\u00e0 dell\u201985,96%, specificit\u00e0 dell\u2019 84,21%.<\/p>\n<p><strong>Conclusioni<\/strong>: i valori R2*, mediante l\u2019utilizzo di IDEAL IQ, sono in grado di predire in modo affidabile l&#8217;espressione di GPC3 prima del campionamento del tessuto o dell&#8217;intervento chirurgico.<\/p>\n<p><strong>Implicazioni<\/strong>: sebbene il meccanismo biofisiologico sottostante la correlazione tra R2* e l&#8217;espressione di GPC3 sia sconosciuto, ci\u00f2 aumenta la possibilit\u00e0 di un monitoraggio non invasivo e quantitativo di questo biomarcatore.<\/p>\n<p>&nbsp;<\/p>\n<h5><span style=\"color: #3366ff;\">Multiphase Liver MRI for Identifying the Macrotrabecular-Massive Subtype of Hepatocellular Carcinoma<\/span><\/h5>\n<p>Mul\u00e9 S, Galletto Pregliasco A, Tenenhaus A, Kharrat R, Amaddeo G, Baranes L, et al. Multiphase Liver MRI for Identifying the Macrotrabecular-Massive Subtype of Hepatocellular Carcinoma. Radiology. 2020 Jun 1;295(3):562\u201371. Available from:<\/p>\n<p><a href=\"https:\/\/pubs.rsna.org\/doi\/10.1148\/radiol.2020192230\">https:\/\/pubs.rsna.org\/doi\/10.1148\/radiol.2020192230<\/a><\/p>\n<p><strong>Parole chiave<\/strong>: RM, macrotrabeculr-massive, HCC, biomarcatore di imaging.<\/p>\n<p><strong>Quesito clinico<\/strong>: un sottotipo istologico aggressivo di HCC chiamato &#8220;macrotrabecular-massive&#8221; (MTM) \u00e8 associato a una scarsa sopravvivenza. Questo sottotipo pu\u00f2 essere diagnosticato con metodi meno invasivi rispetto all\u2019analisi tissutale, inclusa la risonanza magnetica (RM)?<\/p>\n<p><strong>Cosa \u00e8 stato fatto<\/strong>: 152 pazienti con HCC e campioni chirurgici disponibili sono stati valutati con la RM per le caratteristiche associate al sottotipo MTM di HCC.<\/p>\n<p><strong>Come \u00e8 stato fatto<\/strong>: utilizzando analisi di regressione logistica multivariata, sono state identificate una necrosi sostanziale all\u2019imaging, un alto livello sierico di AFP (&gt; 100 ng\/mL) e uno stadio B\/C del Barcelona Clinic Liver Cancer (BCLC) staging system come caratteristiche indipendenti associate al sottotipo MTM di HCC.<\/p>\n<p><strong>Risultati<\/strong>: la necrosi sostanziale, in particolare, aveva odds ratio di 32,65% di sensibilit\u00e0 e 93% di specificit\u00e0 per il sottotipo MTM.\u00a0 Un elevato livello sierico di AFP e uno stadio B\/C di BCLC avevano odds ratio tra 4 e 5 per il sottotipo MTM.<\/p>\n<p><strong>Conclusioni<\/strong>: la necrosi sostanziale, un elevato livello sierico di AFP (&gt; 100 ng\/mL) e uno stadio B\/C di BCLC sono predittori indipendenti per il sottotipo MTM di HCC. Nel contempo, la recidiva precoce e globale del tumore era pi\u00f9 strettamente associata alla presenza di noduli satelliti.<\/p>\n<p><strong>Implicazioni<\/strong>: la necrosi sostanziale in RM \u00e8 un metodo non invasivo per identificare il sottotipo aggressivo MTM di HCC, tuttavia il suo valore prognostico deve ancora essere determinato.<\/p>\n<p>&nbsp;<\/p>\n<h3><span style=\"color: #800080;\"><strong>Liver Vascular Pathologies and Interventional Imaging<\/strong><\/span><\/h3>\n<p>&nbsp;<\/p>\n<h5><span style=\"color: #3366ff;\"><strong>Complications after Liver Transplant Related to Preexisting Conditions: Diagnosis, Treatment, and Prevention<\/strong><\/span><\/h5>\n<p>Horrow MM, Huynh M-HL, Callaghan MM, Rodgers SK. Complications after Liver Transplant Related to Preexisting Conditions: Diagnosis, Treatment, and Prevention. RadioGraphics [Internet]. 2020 May 1 [cited 2020 Jun 17];40(3):895\u2013909. Available from:<\/p>\n<p><a href=\"https:\/\/pubs.rsna.org\/doi\/10.1148\/rg.2019190120\">https:\/\/pubs.rsna.org\/doi\/10.1148\/rg.2019190120<\/a><\/p>\n<p><strong>Parole chiave<\/strong>: vascolarizzazione epatica, trapianto epatico.<\/p>\n<p><strong>Quesito clinico<\/strong>: l\u2019imaging pre-trapianto viene eseguito con TC o risonanza magnetica (RM). Mentre, l&#8217;imaging post-trapianto viene eseguito classicamente con l&#8217;ecografia come modalit\u00e0 di screening per le complicanze delle anastomosi chirurgiche epatiche vascolari e biliari. Quali aspetti post-trapianto sono omessi a causa dell&#8217;uso dell&#8217;ecografia rispetto alla TC o alla RM, e perch\u00e9?<\/p>\n<p><strong>Cosa \u00e8 stato fatto<\/strong>: Horrow et al. forniscono esempi di imaging di condizioni che non si osservano all&#8217;ecografia, ma che possono derivare da una variet\u00e0 di condizioni vascolari preesistenti come una precedente embolizzazione transarteriosa dell&#8217;HCC, il restringimento aterosclerotico di grandi arterie, varianti anatomiche arteriose epatiche, insufficienza<strong>\/<\/strong>trombosi portale o shunt di varici intra-addominali di grandi dimensioni e fenomeni di furto.<\/p>\n<p><strong>Implicazioni<\/strong>: le complicanze post-trapianto correlate a una variet\u00e0 di possibili condizioni preesistenti sono meglio prevenute attraverso il riconoscimento precoce all&#8217;imaging preoperatorio TC o RM, poich\u00e9 potrebbero non essere visualizzate nell&#8217;ecografia post-trapianto.<\/p>\n<p>&nbsp;<\/p>\n<h5><span style=\"color: #3366ff;\"><strong>Transarterial chemoembolization for pulmonary or mediastinal metastases from hepatocellular carcinoma<\/strong><\/span><\/h5>\n<p>Hori A, Ohira R, Nakamura T, Kimura Y, Ueda S, Torii M, et al. Transarterial chemoembolization for pulmonary or mediastinal metastases from hepatocellular carcinoma. Br J Radiol [Internet]. 2020 Jun 1 [cited 2020 Jun 17];93(1110):20190407. Available from:<\/p>\n<p><a href=\"https:\/\/www.birpublications.org\/doi\/abs\/10.1259\/bjr.20190407\">https:\/\/www.birpublications.org\/doi\/abs\/10.1259\/bjr.20190407<\/a><\/p>\n<p><strong>Parole chiave<\/strong>: radiologia interventistica, metastasi da HCC, TACE.<\/p>\n<p><strong>Quesito clinico<\/strong>: gli effetti collaterali dei farmaci sistemici a bersaglio molecolare sulle metastasi da HCC sono frequenti, mentre gli effetti positivi sulle lesioni metastatiche sono limitati. La chemioembolizzazione arteriosa transcatetere (TACE) \u00e8 una procedura eseguita localmente per il trattamento dell&#8217;HCC focale. La TACE pu\u00f2 essere utilizzata per il trattamento di siti metastatici da HCC a livello toracico in modo tale da rinunciare alla necessit\u00e0 di terapie sistemiche a bersaglio molecolare?<\/p>\n<p><strong>Cosa \u00e8 stato fatto<\/strong>: 14 pazienti con HCC e lesioni metastatiche al torace sono stati studiati dopo la TACE in combinazione con la chemioterapia, ma senza alcuna terapia a bersaglio molecolare.<\/p>\n<p><strong>Come \u00e8 stato fatto<\/strong>: Hori et al. hanno utilizzato HepaSphere per l&#8217;embolizzazione e hanno valutato la risposta tumorale locale e gli eventi avversi come endpoint primari secondo i criteri RECIST 1.1 e CTCAE v4. La sopravvivenza globale costituiva un endpoint secondario.<\/p>\n<p><strong>Risultati<\/strong>: i risultati hanno mostrato una sicurezza accettabile, nessuna mortalit\u00e0 a 30 giorni, 7,1% di risposta e un tasso di controllo della malattia entro il primo mese del 100%. La riduzione media delle dimensioni del tumore si \u00e8 verificata ad un tasso del 15,6 +\/- 9,5% entro il primo mese. Il tempo medio di sopravvivenza globale \u00e8 stato di 15 mesi, con tassi di sopravvivenza a 1 anno del 57,1%, a 3 anni del 28,6% e a 5 anni del 19,1%.<\/p>\n<p><strong>Conclusioni<\/strong>: la TACE per HCC \u00e8 sicura ed efficace in caso di metastasi polmonari e mediastiniche.<\/p>\n<p><strong>Implicazioni<\/strong>: nei pazienti con carcinoma epatico metastatico isolato al torace, \u00e8 possibile evitare la terapia a bersaglio molecolare e i suoi numerosi effetti collaterali, optando per la TACE e la chemioterapia. Tuttavia, la realizzabilit\u00e0 della TACE \u00e8 probabilmente limitata dalla posizione delle lesioni metastatiche e dalla vicinanza ai vasi cateterizzabili.<\/p>\n<p>&nbsp;<\/p>\n<h5><span style=\"color: #3366ff;\"><strong>Hepatic\u00a0<\/strong><strong>Vascular Malformation<\/strong><strong>\u00a0Mimics\u00a0<\/strong><strong>PSMA-Positive Prostate Cancer Metastasis<\/strong><\/span><\/h5>\n<p>Hober\u00fcck S, Driesnack S, Seppelt D, Michler E, H\u00f6lscher T, Kotzerke J. Hepatic Vascular Malformation Mimics PSMA-Positive Prostate Cancer Metastasis. Clin Nucl Med [Internet]. 2020 Jun 1 [cited 2020 Jun 17];45(6):e283\u20134. Available from:<\/p>\n<p><a href=\"http:\/\/journals.lww.com\/10.1097\/RLU.0000000000003032\">http:\/\/journals.lww.com\/10.1097\/RLU.0000000000003032<\/a><\/p>\n<p><strong>Parole chiave<\/strong>: metastasi al fegato, medicina nucleare, PET, <em>cancer mimics<\/em>.<\/p>\n<p><strong>Cosa \u00e8 stato fatto<\/strong>: un paziente con carcinoma prostatico \u00e8 stato sottoposto a PET\/TC con il radiofarmaco 68-Ga-PSMA, che utilizza l&#8217;antigene di membrana specifico della prostata (PSMA) per colpire il carcinoma prostatico e le lesioni metastatiche.<\/p>\n<p><strong>Risultati<\/strong>: la PET\/TC del paziente ha mostrato carcinoma primitivo <em>PSMA<\/em><em>-avid<\/em>, una lesione metastatica ossea solitaria a livello vertebrale e una lesione sospetta <em>PSMA<\/em><em>-avid<\/em> nel fegato, che deponeva per metastasi epatica. Tuttavia, sulla base della precedente TC con mezzo di contrasto, dell\u2019ecografia con mezzo di contrasto e del follow-up PSMA-PET\/TC dopo privazione di androgeni, la lesione intraepatica \u00e8 stata diagnosticata come una malformazione vascolare che imitava metabolicamente le metastasi epatiche del carcinoma prostatico.<\/p>\n<p><strong>Implicazioni<\/strong>: le malformazioni vascolari epatiche possono trattenere radiofarmaci come 68-Ga-PSMA, e forse altri ancora, e presentarsi come lesioni false positive nelle scansioni PET\/TC di stadiazione.<\/p>\n","protected":false},"excerpt":{"rendered":"&nbsp; Liver CT Imaging &nbsp; Variability of quantitative measurements of metastatic liver lesions: a multi-radiation-dose-level [&hellip;]","protected":false},"author":4,"featured_media":2952,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[206],"tags":[],"class_list":["post-3436","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-categorizzato"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Novit\u00e0 nell&#039;imaging epatico? - ACORE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acoredu.graphich.agency\/it\/whats-new-in-liver-imaging-july-2020-italian\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Novit\u00e0 nell&#039;imaging epatico? - ACORE\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Liver CT Imaging &nbsp; Variability of quantitative measurements of metastatic liver lesions: a multi-radiation-dose-level [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acoredu.graphich.agency\/it\/whats-new-in-liver-imaging-july-2020-italian\/\" \/>\n<meta property=\"og:site_name\" content=\"ACORE\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-05T03:10:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-06T13:23:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/acoredu.graphich.agency\/wp-content\/uploads\/2020\/07\/ct-scan-workstation-with-ct-whole-abdomen-background_t20_ZVGWkj.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2030\" \/>\n\t<meta property=\"og:image:height\" content=\"1457\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Moataz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Moataz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acoredu.graphich.agency\\\/it\\\/whats-new-in-liver-imaging-july-2020-italian\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acoredu.graphich.agency\\\/it\\\/whats-new-in-liver-imaging-july-2020-italian\\\/\"},\"author\":{\"name\":\"Moataz\",\"@id\":\"https:\\\/\\\/acoredu.graphich.agency\\\/#\\\/schema\\\/person\\\/eedb7548e3acfc9b6c939a35427f799f\"},\"headline\":\"Novit\u00e0 nell&#8217;imaging epatico?\",\"datePublished\":\"2020-07-05T03:10:53+00:00\",\"dateModified\":\"2020-07-06T13:23:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acoredu.graphich.agency\\\/it\\\/whats-new-in-liver-imaging-july-2020-italian\\\/\"},\"wordCount\":2818,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/acoredu.graphich.agency\\\/it\\\/whats-new-in-liver-imaging-july-2020-italian\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/acoredu.graphich.agency\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/ct-scan-workstation-with-ct-whole-abdomen-background_t20_ZVGWkj.jpg\",\"articleSection\":[\"Non categorizzato\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/acoredu.graphich.agency\\\/it\\\/whats-new-in-liver-imaging-july-2020-italian\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acoredu.graphich.agency\\\/it\\\/whats-new-in-liver-imaging-july-2020-italian\\\/\",\"url\":\"https:\\\/\\\/acoredu.graphich.agency\\\/it\\\/whats-new-in-liver-imaging-july-2020-italian\\\/\",\"name\":\"Novit\u00e0 nell'imaging epatico? - ACORE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acoredu.graphich.agency\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acoredu.graphich.agency\\\/it\\\/whats-new-in-liver-imaging-july-2020-italian\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acoredu.graphich.agency\\\/it\\\/whats-new-in-liver-imaging-july-2020-italian\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/acoredu.graphich.agency\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/ct-scan-workstation-with-ct-whole-abdomen-background_t20_ZVGWkj.jpg\",\"datePublished\":\"2020-07-05T03:10:53+00:00\",\"dateModified\":\"2020-07-06T13:23:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/acoredu.graphich.agency\\\/#\\\/schema\\\/person\\\/eedb7548e3acfc9b6c939a35427f799f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acoredu.graphich.agency\\\/it\\\/whats-new-in-liver-imaging-july-2020-italian\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acoredu.graphich.agency\\\/it\\\/whats-new-in-liver-imaging-july-2020-italian\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/acoredu.graphich.agency\\\/it\\\/whats-new-in-liver-imaging-july-2020-italian\\\/#primaryimage\",\"url\":\"https:\\\/\\\/acoredu.graphich.agency\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/ct-scan-workstation-with-ct-whole-abdomen-background_t20_ZVGWkj.jpg\",\"contentUrl\":\"https:\\\/\\\/acoredu.graphich.agency\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/ct-scan-workstation-with-ct-whole-abdomen-background_t20_ZVGWkj.jpg\",\"width\":2030,\"height\":1457},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acoredu.graphich.agency\\\/it\\\/whats-new-in-liver-imaging-july-2020-italian\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acoredu.graphich.agency\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Novit\u00e0 nell&#8217;imaging epatico?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acoredu.graphich.agency\\\/#website\",\"url\":\"https:\\\/\\\/acoredu.graphich.agency\\\/\",\"name\":\"ACORE\",\"description\":\"Radiology education for everyone, everywhere!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acoredu.graphich.agency\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acoredu.graphich.agency\\\/#\\\/schema\\\/person\\\/eedb7548e3acfc9b6c939a35427f799f\",\"name\":\"Moataz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aa8de30de126d81547e191c9033e8eff7f4120e31d5ffbc26635fdafe886af98?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aa8de30de126d81547e191c9033e8eff7f4120e31d5ffbc26635fdafe886af98?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aa8de30de126d81547e191c9033e8eff7f4120e31d5ffbc26635fdafe886af98?s=96&d=mm&r=g\",\"caption\":\"Moataz\"},\"url\":\"https:\\\/\\\/acoredu.graphich.agency\\\/it\\\/author\\\/moataz\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Novit\u00e0 nell'imaging epatico? - ACORE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acoredu.graphich.agency\/it\/whats-new-in-liver-imaging-july-2020-italian\/","og_locale":"it_IT","og_type":"article","og_title":"Novit\u00e0 nell'imaging epatico? - ACORE","og_description":"&nbsp; Liver CT Imaging &nbsp; Variability of quantitative measurements of metastatic liver lesions: a multi-radiation-dose-level [&hellip;]","og_url":"https:\/\/acoredu.graphich.agency\/it\/whats-new-in-liver-imaging-july-2020-italian\/","og_site_name":"ACORE","article_published_time":"2020-07-05T03:10:53+00:00","article_modified_time":"2020-07-06T13:23:45+00:00","og_image":[{"width":2030,"height":1457,"url":"https:\/\/acoredu.graphich.agency\/wp-content\/uploads\/2020\/07\/ct-scan-workstation-with-ct-whole-abdomen-background_t20_ZVGWkj.jpg","type":"image\/jpeg"}],"author":"Moataz","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Moataz","Tempo di lettura stimato":"14 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acoredu.graphich.agency\/it\/whats-new-in-liver-imaging-july-2020-italian\/#article","isPartOf":{"@id":"https:\/\/acoredu.graphich.agency\/it\/whats-new-in-liver-imaging-july-2020-italian\/"},"author":{"name":"Moataz","@id":"https:\/\/acoredu.graphich.agency\/#\/schema\/person\/eedb7548e3acfc9b6c939a35427f799f"},"headline":"Novit\u00e0 nell&#8217;imaging epatico?","datePublished":"2020-07-05T03:10:53+00:00","dateModified":"2020-07-06T13:23:45+00:00","mainEntityOfPage":{"@id":"https:\/\/acoredu.graphich.agency\/it\/whats-new-in-liver-imaging-july-2020-italian\/"},"wordCount":2818,"commentCount":0,"image":{"@id":"https:\/\/acoredu.graphich.agency\/it\/whats-new-in-liver-imaging-july-2020-italian\/#primaryimage"},"thumbnailUrl":"https:\/\/acoredu.graphich.agency\/wp-content\/uploads\/2020\/07\/ct-scan-workstation-with-ct-whole-abdomen-background_t20_ZVGWkj.jpg","articleSection":["Non categorizzato"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/acoredu.graphich.agency\/it\/whats-new-in-liver-imaging-july-2020-italian\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/acoredu.graphich.agency\/it\/whats-new-in-liver-imaging-july-2020-italian\/","url":"https:\/\/acoredu.graphich.agency\/it\/whats-new-in-liver-imaging-july-2020-italian\/","name":"Novit\u00e0 nell'imaging epatico? - ACORE","isPartOf":{"@id":"https:\/\/acoredu.graphich.agency\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acoredu.graphich.agency\/it\/whats-new-in-liver-imaging-july-2020-italian\/#primaryimage"},"image":{"@id":"https:\/\/acoredu.graphich.agency\/it\/whats-new-in-liver-imaging-july-2020-italian\/#primaryimage"},"thumbnailUrl":"https:\/\/acoredu.graphich.agency\/wp-content\/uploads\/2020\/07\/ct-scan-workstation-with-ct-whole-abdomen-background_t20_ZVGWkj.jpg","datePublished":"2020-07-05T03:10:53+00:00","dateModified":"2020-07-06T13:23:45+00:00","author":{"@id":"https:\/\/acoredu.graphich.agency\/#\/schema\/person\/eedb7548e3acfc9b6c939a35427f799f"},"breadcrumb":{"@id":"https:\/\/acoredu.graphich.agency\/it\/whats-new-in-liver-imaging-july-2020-italian\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acoredu.graphich.agency\/it\/whats-new-in-liver-imaging-july-2020-italian\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/acoredu.graphich.agency\/it\/whats-new-in-liver-imaging-july-2020-italian\/#primaryimage","url":"https:\/\/acoredu.graphich.agency\/wp-content\/uploads\/2020\/07\/ct-scan-workstation-with-ct-whole-abdomen-background_t20_ZVGWkj.jpg","contentUrl":"https:\/\/acoredu.graphich.agency\/wp-content\/uploads\/2020\/07\/ct-scan-workstation-with-ct-whole-abdomen-background_t20_ZVGWkj.jpg","width":2030,"height":1457},{"@type":"BreadcrumbList","@id":"https:\/\/acoredu.graphich.agency\/it\/whats-new-in-liver-imaging-july-2020-italian\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acoredu.graphich.agency\/"},{"@type":"ListItem","position":2,"name":"Novit\u00e0 nell&#8217;imaging epatico?"}]},{"@type":"WebSite","@id":"https:\/\/acoredu.graphich.agency\/#website","url":"https:\/\/acoredu.graphich.agency\/","name":"ACORE","description":"Radiology education for everyone, everywhere!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acoredu.graphich.agency\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/acoredu.graphich.agency\/#\/schema\/person\/eedb7548e3acfc9b6c939a35427f799f","name":"Moataz","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/aa8de30de126d81547e191c9033e8eff7f4120e31d5ffbc26635fdafe886af98?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/aa8de30de126d81547e191c9033e8eff7f4120e31d5ffbc26635fdafe886af98?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/aa8de30de126d81547e191c9033e8eff7f4120e31d5ffbc26635fdafe886af98?s=96&d=mm&r=g","caption":"Moataz"},"url":"https:\/\/acoredu.graphich.agency\/it\/author\/moataz\/"}]}},"_links":{"self":[{"href":"https:\/\/acoredu.graphich.agency\/it\/wp-json\/wp\/v2\/posts\/3436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acoredu.graphich.agency\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acoredu.graphich.agency\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acoredu.graphich.agency\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/acoredu.graphich.agency\/it\/wp-json\/wp\/v2\/comments?post=3436"}],"version-history":[{"count":4,"href":"https:\/\/acoredu.graphich.agency\/it\/wp-json\/wp\/v2\/posts\/3436\/revisions"}],"predecessor-version":[{"id":3644,"href":"https:\/\/acoredu.graphich.agency\/it\/wp-json\/wp\/v2\/posts\/3436\/revisions\/3644"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acoredu.graphich.agency\/it\/wp-json\/wp\/v2\/media\/2952"}],"wp:attachment":[{"href":"https:\/\/acoredu.graphich.agency\/it\/wp-json\/wp\/v2\/media?parent=3436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acoredu.graphich.agency\/it\/wp-json\/wp\/v2\/categories?post=3436"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acoredu.graphich.agency\/it\/wp-json\/wp\/v2\/tags?post=3436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}