{"id":14958,"date":"2021-08-25T16:12:16","date_gmt":"2021-08-25T21:12:16","guid":{"rendered":"https:\/\/acoredu.graphich.agency\/?p=14958"},"modified":"2021-08-25T16:12:16","modified_gmt":"2021-08-25T21:12:16","slug":"14958","status":"publish","type":"post","link":"https:\/\/acoredu.graphich.agency\/it\/14958\/","title":{"rendered":""},"content":{"rendered":"<p><strong>Imaging of drug mules<\/strong><\/p>\n<p><strong>Malhotra R, Singh A. Imaging of drug mules. <\/strong><strong>Emerg Radiol. 2021 Aug;28(4):809-814.<\/strong><\/p>\n<p><strong>\u00a0<\/strong>Questo articolo di un gruppo del Massachusetts General Hospital descrive in dettaglio i reperti di imaging nei \u201cdrug mules\u201d (corrieri della droga), individui che contrabbandano sostanze illecite trasportandole all\u2019interno del corpo. Cocaina, eroina, metanfetamina e hashish sono le droghe pi\u00f9 diffuse trasportate dai corrieri della droga. La radiografia ha una sensibilit\u00e0 fino al 90% nell\u2019individuazione delle sostanze nascoste, anche la TC a basso dosaggio risulta accurata nel localizzare i pacchetti interni. L&#8217;articolo inizia descrivendo la diffusione mondiale della droga, soffermandosi poi sull&#8217;importanza dei radiologi nel rilevamento delle sostanze di contrabbando. Gli autori sottolineano come i falsi negativi comportano, oltre a consentire il traffico illecito nella comunit\u00e0, il rischio di danno agli organi interni del paziente. Successivamente, vengono discusse in modo approfondito, le tecniche di contrabbando che includono la deglutizione, il riempimento rettale e vaginale. I contrabbandieri sono diventati esperti del rilevamento radiologico e impiegano tecniche per ridurre la differenza di radiodensit\u00e0 tra i farmaci e le feci circostanti. Gli autori raccomandano una radiografia come esame iniziale, seguita da una TC per convalidare la diagnosi ed escludere complicazioni, in particolare l\u2019ostruzione e la perforazione intestinale. L&#8217;articolo discute diversi reperti di imaging, il pi\u00f9 comune dei quali \u00e8 il &#8220;segno del tic tac&#8221;, figure oblunghe lisce delineate dall&#8217;aria. Viene discussa inoltre l\u2019aspetto di diverse droghe, l&#8217;hashish che ha la pi\u00f9 alta densit\u00e0, seguita dalla cocaina e dall&#8217;eroina. In conclusione, gli autori affermano che \u00e8 necessario un approccio multimodale per identificare e trattare con precisione il contrabbando interno di sostanze illecite.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Imaging findings of benign and malignant pediatric splenic lesions<\/strong><\/p>\n<p><strong>Ozkale Yavuz O, Ozcan HN, Oguz B, Ayaz E, Ekinci S, Ciftci TT, Haliloglu M. Imaging findings of benign and malignant pediatric splenic lesions. <\/strong><strong>Abdom Radiol (NY). 2021 Jul;46(7):3245-3252.<\/strong><\/p>\n<p>Questo articolo riguarda l&#8217;imaging pediatrico della milza, che comprende un&#8217;ampia variet\u00e0 di patologie, alcune benigne e altre maligne. Le cisti sono le lesioni spleniche benigne pi\u00f9 comuni, seguite da emangiomi e malformazioni linfatiche. La maggior parte delle condizioni maligne della milza \u00e8 correlata alla leucemia e al linfoma, con l&#8217;angiosarcoma che rappresenta il tumore splenico primitivo pi\u00f9 comune. L&#8217;articolo commenta le caratteristiche all\u2019 imaging di ciascuna di queste patologie, nonch\u00e9 i reperti meno comuni come la trasformazione nodulare angiomatoide sclerosante della milza (SANT), i tumori miofibroblastici infiammatori e gli amartomi. Poich\u00e9 questo articolo si riferisce all&#8217;imaging pediatrico, si concentra principalmente sui reperti dell\u2019ecografia e della risonanza magnetica.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>A review of optimal evaluation and treatment of suspected esophageal food impaction<\/strong><\/p>\n<p><strong>Lake M, Smoot D, O&#8217;Halloran P, Shortsleeve M. A review of optimal evaluation and treatment of suspected esophageal food impaction. <\/strong><strong>Emerg Radiol. 2021 Apr;28(2):401-407.<\/strong><\/p>\n<p>Questo articolo tratta la fluoroscopia contrasto-guidata per valutare e trattare le ostruzioni esofagee. Mentre le ostruzioni esofagee del tratto prossimale e medio richiedono un intervento otorinolaringoiatrico e gastrointestinale, le ostruzioni distali (inferiormente all&#8217;arco aortico) possono essere gestite dal radiologo con una disostruzione sotto guida fluoroscopica. La tecnica, descritta dagli autori, utilizza una combinazione di glucagone per via endovenosa, materiale effervescente e acqua per rimuovere l&#8217;ostruzione. Il glucagone rilassa la muscolatura liscia esofagea, l&#8217;agente effervescente dilata l&#8217;esofago e l&#8217;acqua aumenta la pressione idrostatica sopra il bolo. Gli autori citano un tasso di successo di disostruzione del 56% in 252 tentativi negli ultimi 32 anni presso il loro istituto. Vengono inoltre descritte, in modo approfondito, le indicazioni, le tecniche e le controindicazioni per la disostruzione esofagea fluoroscopica. Oltre alla localizzazione, le principali controindicazioni includono l&#8217;ostruzione dovuta a stenosi o corpi estranei taglienti.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Traumatic abdominal wall injuries\u2014a primer for radiologists<\/strong><\/p>\n<p><strong>Steenburg SD, Padilla-Jones B, Lee JT, Petersen MJ, Boutselis AG, Lay SE, Dunkle JW, Chong S. Traumatic abdominal wall injuries-a primer for radiologists. <\/strong><strong>Emerg Radiol. 2021 Apr;28(2):361-371.<\/strong><\/p>\n<p>Questo articolo sottolinea l&#8217;importanza della valutazione della parete addominale, e l\u2019insieme delle lesioni che possono verificarsi, in caso di un trauma chiuso, nonostante sia comunque fondamentale valutare gli organi interni.<\/p>\n<p>Le lesioni della parete addominale si verificano in circa il 10% dei pazienti con trauma chiuso e possono variare da contusioni della parete addominale e stiramenti muscolari, a ematomi e rottura della parete addominale. Gli autori trattano la valutazione clinica, i reperti di imaging e l&#8217;approccio chirurgico a queste lesioni. La forma pi\u00f9 grave di lesione della parete addominale \u00e8 l&#8217;ernia traumatica, e pu\u00f2 essere osservata fino all&#8217;1,5% dei pazienti con trauma addominale chiuso. Ci\u00f2 si verifica pi\u00f9 comunemente nel triangolo lombare inferiore, in seguito ad una collisione del passeggero all\u2019interno di un veicolo<em>.<\/em> L&#8217;identificazione delle ernie traumatiche \u00e8 importante poich\u00e9, fino ad un 25% dei casi, andr\u00e0 incontro ad incarcerazione o strangolamento se non trattate. Il radiologo non dovrebbe fermarsi alla ricerca di lesioni agli organi interni, poich\u00e9 questo potrebbe portare ad un aumento del rischio di traumi di alto grado della parete addominale<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Appendicitis and beyond: a pictorial review of various appendiceal abnormalities<\/strong><\/p>\n<p><strong>Fenwick AKC, Hartery A. Appendicitis and beyond: a pictorial review of various appendiceal abnormalities. <\/strong><strong>Emerg Radiol. 2021 Jun;28(3):651-664.\u00a0<\/strong><\/p>\n<p>Mentre l&#8217;appendicite \u00e8 il processo pi\u00f9 comune che colpisce l&#8217;appendice, questo articolo esamina un&#8217;ampia gamma di patologie appendicolari aggiuntive, benigne e maligne. Gli autori iniziano trattando l&#8217;anatomia dell&#8217;appendice, che \u00e8 fondamentale per comprendere la patologia che pu\u00f2 verificarsi. L&#8217;appendicite acuta viene discussa per prima, con le sue caratteristiche cliniche e di imaging, nonch\u00e9 le sue complicazioni come la perforazione. Si passa quindi ad altre alterazioni infiammatorie dell&#8217;appendice come diverticolite appendicolare, appendicite del moncone, l\u2019appendicite da corpo estraneo, il morbo di Crohn e le ernie appendicolari, che possono verificarsi sia attraverso la parete addominale che nel canale inguinale. Vengono quindi discusse le condizioni neoplastiche, inclusi i tumori neuroendocrini, le neoplasie epiteliali mucinose e non mucinose e il linfoma.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Hemorrhagic cholecystitis: ultrasound and CT imaging findings\u2014a retrospective case review series<\/strong><\/p>\n<p><strong>Ram\u00edrez Calder\u00f3n JZ, Mart\u00ednez Chamorro E, Ib\u00e1\u00f1ez Sanz L, Albillos Merino JC, Borruel Nacenta S. Hemorrhagic cholecystitis: ultrasound and CT imaging findings-a retrospective case review series. <\/strong><strong>Emerg Radiol. 2021 Jun;28(3):613-620.<\/strong><\/p>\n<p>Questo articolo espone una delle complicate presentazioni della colecistite acuta, la colecistite emorragica. Gli autori hanno raccolto 11 casi in un periodo di sei anni, come confermato dal referto patologico. La colecistite emorragica \u00e8 stata pi\u00f9 comunemente osservata nei pazienti con colelitiasi e in terapia anticoagulante. Viene presentata prima l&#8217;eziologia, probabilmente dovuta a modificazioni infiammatorie della parete della colecisti che possono portare ad ischemia della parete ed emorragia. Nei loro casi, l&#8217;ecografia era una modalit\u00e0 di imaging di prima linea per diversi pazienti, tutti alla fine sono stati sottoposti a TC, ed un paziente a RM. Gli autori affermano che l&#8217;ecografia pu\u00f2 rivelare segni tipici di colecistite acuta, ed ulteriori reperti possono includere detriti iperecogeni all&#8217;interno del lume che possono consistere in cataboliti sanguigni. La TC pu\u00f2 evidenziare emobilia o materiale intraluminale con un livello di ematocrito. L&#8217;emoperitoneo pu\u00f2 suggerire la perforazione nel contesto della colecistite emorragica. La risonanza magnetica in genere non viene eseguita per il sospetto di colecistite emorragica a causa dello scenario clinico e della capacit\u00e0 della TC e dell\u2019ecografia di diagnosticare la colecistite, ma la RM \u00e8 il miglior test di imaging per differenziare l&#8217;emorragia. Il trattamento di scelta \u00e8 la colecistectomia in urgenza a causa dell&#8217;elevata morbilit\u00e0 e mortalit\u00e0 della colecistite emorragica.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>CT appearance of gastrointestinal tract mucormycosis<\/strong><\/p>\n<p><strong>Ghuman SS, Sindhu P, Buxi TBS, Sheth S, Yadav A, Rawat KS, Sud S. CT appearance of gastrointestinal tract mucormycosis. <\/strong><strong>Abdom Radiol (NY). 2021 May;46(5):1837-1845<\/strong>.<\/p>\n<p>Si pensa comunemente che la mucormicosi colpisca i seni paranasali e i polmoni, tuttavia questo articolo esamina i reperti di imaging quando viene colpito il tratto gastrointestinale. La mucormicosi \u00e8 pi\u00f9 comunemente osservata nei pazienti con un sistema immunitario compromesso. All&#8217;interno del tratto gastrointestinale, lo stomaco \u00e8 l&#8217;organo pi\u00f9 comunemente colpito, seguito dal colon, intestino tenue ed esofago.<\/p>\n<p>I reperti TC comprendono pneumatosi, diminuzione dell&#8217;enhancement di parete e l\u2019ispessimento della parete intestinale. \u00a0Poich\u00e9 questi risultati sono in gran parte aspecifici, l&#8217;anamnesi clinica \u00e8 importante. Gli autori includono esempi di tutti i reperti di imaging e diverse manifestazioni nelle diverse parti del tratto gastrointestinale. Sebbene la mucormicosi addominale sia rara, ha un alto tasso di mortalit\u00e0 e dovrebbe essere sospettata nei pazienti immunocompromessi con ischemia intestinale inspiegabile.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Caustic ingestion: CT findings of esophageal injuries and thoracic complications<\/strong><\/p>\n<p><strong>Cutaia G, Messina M, Rubino S, Reitano E, Salvaggio L, Costanza I, Agnello F, La Grutta L, Midiri M, Salvaggio G, Gargano R. Caustic ingestion: CT findings of esophageal injuries and thoracic complications. Emerg Radiol. 2021 Aug;28(4):845-856.<\/strong><\/p>\n<p>L&#8217;ingestione di sostanze caustiche pu\u00f2 essere accidentale o intenzionale e pu\u00f2 causare gravi danni in tutto il sistema gastrointestinale, questo articolo si concentra sui reperti esofagei e toracici. Le sostanze caustiche possono causare danni attraverso molti meccanismi che includono la necrosi colliquativa, la saponificazione dei grassi, la denaturazione delle proteine \u200b\u200be la trombosi dei vasi sanguigni. Gli autori citano le linee guida della World Society of Emergency Surgery secondo le quali la TC dovrebbe essere lo studio di imaging iniziale per valutare un&#8217;emergenza chirurgica, seguita dall&#8217;endoscopia nel caso in cui non venga rilevato nulla. Le radiografie possono anche essere utili per rilevare la presenza di pneumomediastino o versamenti pleurici in caso di perforazione. Per la TC, gli autori raccomandano uno studio trifasico (scansione senza mezzo di contrasto, e con contrasto in fase arteriosa e venosa). Gli autori inoltre raccomandano, in caso di sospetta perforazione, anche la somministrazione di mezzo di contrasto per via orale. L&#8217;articolo discute quindi i diversi reperti di imaging che possono essere osservati nelle lesioni acute, subacute e croniche dell&#8217;esofago. Oltre alle lesioni esofagee, gli autori discutono anche le lesioni mediastiniche e le fistole respiratorie.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>A comprehensive radiologic review of abdominal and pelvic torsions<\/strong><\/p>\n<p><strong>Bonney R, Revels JW, Wang SS, Lussier R, Dey CB, Katz DS, Moshiri M. A comprehensive radiologic review of abdominal and pelvic torsions. <\/strong><strong>Abdom Radiol (NY). 2021 Jun;46(6):2942-2960.\u00a0<\/strong><\/p>\n<p>Questa review discute i vari tipi di torsioni che possono verificarsi in tutto l&#8217;addome e pelvi, oltre la torsione ovarica e testicolare. I reperti dell&#8217;imaging sono importanti poich\u00e9 alcune delle torsioni meno comuni potrebbero non essere sospettate clinicamente. L&#8217;articolo afferma che quasi ciascuno degli organi \u00e8 suscettibile di torsione, che pu\u00f2 portare a significativa morbilit\u00e0 e mortalit\u00e0 di soggetti non identificati e prontamente trattati. Una delle caratteristiche di imaging comuni alle varie torsioni \u00e8 il segno del &#8220;vortice&#8221;, la torsione del peduncolo vascolare. L&#8217;articolo discute i risultati di imaging della torsione in tutto il tratto gastrointestinale dallo stomaco al colon. L&#8217;articolo discute quindi la torsione dell&#8217;omento, della milza, della colecisti, del pancreas, dei reni, del fegato trapiantato, delle ovaie, delle tube di Falloppio, dei fibromi e dei testicoli. In conclusione, gli autori dichiarano l&#8217;importanza dei radiologi nell&#8217;identificare la torsione degli organi addominali, poich\u00e9 molte di esse sono rare e probabilmente non sospettate clinicamente nell&#8217;esame iniziale del dolore addominale acuto.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Intraperitoneal focal fat infarction: the great mimicker in the acute setting<\/strong><\/p>\n<p><strong>Lazaridou E, Aslanidi C, Mellou V, Athanasiou S, Exarhos D. Intraperitoneal focal fat infarction: the great mimicker in the acute setting. <\/strong><strong>Emerg Radiol. 2021 Feb;28(1):201-207.\u00a0<\/strong><\/p>\n<p>Questo articolo discute, l&#8217;infarto del grasso intraperitoneale, che comprende condizioni come l&#8217;appendagite epiploica, l&#8217;infarto omentale e l&#8217;appendagite perigastrica lungo le stesse linee della torsione. La maggior parte dei casi di infarto focale del grasso sono legati alla torsione con occlusione vascolare, pi\u00f9 comunemente venosa, che pu\u00f2 portare all&#8217;infarto del grande omento, delle appendici epiploiche e, pi\u00f9 raramente, del legamento falciforme. Queste condizioni autolimitanti possono mimare altre patologie emergenti come l&#8217;appendicite o la diverticolite e l&#8217;imaging \u00e8 importante per prevenire interventi chirurgici non necessari. L&#8217;articolo discute la presentazione clinica, nonch\u00e9 i protocolli di ultrasuoni, TC e RM e i risultati di ciascuna delle condizioni di cui sopra. L&#8217;imaging ha un&#8217;elevata sensibilit\u00e0 e specificit\u00e0 e una diagnosi corretta \u00e8 fondamentale per prevenire interventi non necessari.<\/p>\n","protected":false},"excerpt":{"rendered":"Imaging of drug mules Malhotra R, Singh A. Imaging of drug mules. Emerg Radiol. 2021 [&hellip;]","protected":false},"author":4703,"featured_media":14785,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[206],"tags":[],"class_list":["post-14958","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-categorizzato"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>- ACORE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acoredu.graphich.agency\/it\/14958\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"- ACORE\" \/>\n<meta property=\"og:description\" content=\"Imaging of drug mules Malhotra R, Singh A. Imaging of drug mules. Emerg Radiol. 2021 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acoredu.graphich.agency\/it\/14958\/\" \/>\n<meta property=\"og:site_name\" content=\"ACORE\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-25T21:12:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/acoredu.graphich.agency\/wp-content\/uploads\/2021\/08\/doctors-discussing-report-about-a-patient-at-table-2PL7TGF-700x467-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"467\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"munevver\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"munevver\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acoredu.graphich.agency\\\/it\\\/14958\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acoredu.graphich.agency\\\/it\\\/14958\\\/\"},\"author\":{\"name\":\"munevver\",\"@id\":\"https:\\\/\\\/acoredu.graphich.agency\\\/#\\\/schema\\\/person\\\/bef38964e060564cdb92fa9703a2e913\"},\"headline\":\"Nessun titolo\",\"datePublished\":\"2021-08-25T21:12:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acoredu.graphich.agency\\\/it\\\/14958\\\/\"},\"wordCount\":1997,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/acoredu.graphich.agency\\\/it\\\/14958\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/acoredu.graphich.agency\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/doctors-discussing-report-about-a-patient-at-table-2PL7TGF-700x467-1.jpg\",\"articleSection\":[\"Non categorizzato\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/acoredu.graphich.agency\\\/it\\\/14958\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acoredu.graphich.agency\\\/it\\\/14958\\\/\",\"url\":\"https:\\\/\\\/acoredu.graphich.agency\\\/it\\\/14958\\\/\",\"name\":\"- ACORE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acoredu.graphich.agency\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acoredu.graphich.agency\\\/it\\\/14958\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acoredu.graphich.agency\\\/it\\\/14958\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/acoredu.graphich.agency\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/doctors-discussing-report-about-a-patient-at-table-2PL7TGF-700x467-1.jpg\",\"datePublished\":\"2021-08-25T21:12:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/acoredu.graphich.agency\\\/#\\\/schema\\\/person\\\/bef38964e060564cdb92fa9703a2e913\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acoredu.graphich.agency\\\/it\\\/14958\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/acoredu.graphich.agency\\\/it\\\/14958\\\/#primaryimage\",\"url\":\"https:\\\/\\\/acoredu.graphich.agency\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/doctors-discussing-report-about-a-patient-at-table-2PL7TGF-700x467-1.jpg\",\"contentUrl\":\"https:\\\/\\\/acoredu.graphich.agency\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/doctors-discussing-report-about-a-patient-at-table-2PL7TGF-700x467-1.jpg\",\"width\":700,\"height\":467},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acoredu.graphich.agency\\\/#website\",\"url\":\"https:\\\/\\\/acoredu.graphich.agency\\\/\",\"name\":\"ACORE\",\"description\":\"Radiology education for everyone, everywhere!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acoredu.graphich.agency\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acoredu.graphich.agency\\\/#\\\/schema\\\/person\\\/bef38964e060564cdb92fa9703a2e913\",\"name\":\"munevver\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/15e80d6bc39fa14dc9466c462483cd9f9dc7289c1879964cd7351e859f1b5db7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/15e80d6bc39fa14dc9466c462483cd9f9dc7289c1879964cd7351e859f1b5db7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/15e80d6bc39fa14dc9466c462483cd9f9dc7289c1879964cd7351e859f1b5db7?s=96&d=mm&r=g\",\"caption\":\"munevver\"},\"url\":\"https:\\\/\\\/acoredu.graphich.agency\\\/it\\\/author\\\/munevver\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"- ACORE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acoredu.graphich.agency\/it\/14958\/","og_locale":"it_IT","og_type":"article","og_title":"- ACORE","og_description":"Imaging of drug mules Malhotra R, Singh A. Imaging of drug mules. Emerg Radiol. 2021 [&hellip;]","og_url":"https:\/\/acoredu.graphich.agency\/it\/14958\/","og_site_name":"ACORE","article_published_time":"2021-08-25T21:12:16+00:00","og_image":[{"width":700,"height":467,"url":"https:\/\/acoredu.graphich.agency\/wp-content\/uploads\/2021\/08\/doctors-discussing-report-about-a-patient-at-table-2PL7TGF-700x467-1.jpg","type":"image\/jpeg"}],"author":"munevver","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"munevver","Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acoredu.graphich.agency\/it\/14958\/#article","isPartOf":{"@id":"https:\/\/acoredu.graphich.agency\/it\/14958\/"},"author":{"name":"munevver","@id":"https:\/\/acoredu.graphich.agency\/#\/schema\/person\/bef38964e060564cdb92fa9703a2e913"},"headline":"Nessun titolo","datePublished":"2021-08-25T21:12:16+00:00","mainEntityOfPage":{"@id":"https:\/\/acoredu.graphich.agency\/it\/14958\/"},"wordCount":1997,"commentCount":0,"image":{"@id":"https:\/\/acoredu.graphich.agency\/it\/14958\/#primaryimage"},"thumbnailUrl":"https:\/\/acoredu.graphich.agency\/wp-content\/uploads\/2021\/08\/doctors-discussing-report-about-a-patient-at-table-2PL7TGF-700x467-1.jpg","articleSection":["Non categorizzato"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/acoredu.graphich.agency\/it\/14958\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/acoredu.graphich.agency\/it\/14958\/","url":"https:\/\/acoredu.graphich.agency\/it\/14958\/","name":"- ACORE","isPartOf":{"@id":"https:\/\/acoredu.graphich.agency\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acoredu.graphich.agency\/it\/14958\/#primaryimage"},"image":{"@id":"https:\/\/acoredu.graphich.agency\/it\/14958\/#primaryimage"},"thumbnailUrl":"https:\/\/acoredu.graphich.agency\/wp-content\/uploads\/2021\/08\/doctors-discussing-report-about-a-patient-at-table-2PL7TGF-700x467-1.jpg","datePublished":"2021-08-25T21:12:16+00:00","author":{"@id":"https:\/\/acoredu.graphich.agency\/#\/schema\/person\/bef38964e060564cdb92fa9703a2e913"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acoredu.graphich.agency\/it\/14958\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/acoredu.graphich.agency\/it\/14958\/#primaryimage","url":"https:\/\/acoredu.graphich.agency\/wp-content\/uploads\/2021\/08\/doctors-discussing-report-about-a-patient-at-table-2PL7TGF-700x467-1.jpg","contentUrl":"https:\/\/acoredu.graphich.agency\/wp-content\/uploads\/2021\/08\/doctors-discussing-report-about-a-patient-at-table-2PL7TGF-700x467-1.jpg","width":700,"height":467},{"@type":"WebSite","@id":"https:\/\/acoredu.graphich.agency\/#website","url":"https:\/\/acoredu.graphich.agency\/","name":"ACORE","description":"Radiology education for everyone, everywhere!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acoredu.graphich.agency\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/acoredu.graphich.agency\/#\/schema\/person\/bef38964e060564cdb92fa9703a2e913","name":"munevver","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/15e80d6bc39fa14dc9466c462483cd9f9dc7289c1879964cd7351e859f1b5db7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/15e80d6bc39fa14dc9466c462483cd9f9dc7289c1879964cd7351e859f1b5db7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/15e80d6bc39fa14dc9466c462483cd9f9dc7289c1879964cd7351e859f1b5db7?s=96&d=mm&r=g","caption":"munevver"},"url":"https:\/\/acoredu.graphich.agency\/it\/author\/munevver\/"}]}},"_links":{"self":[{"href":"https:\/\/acoredu.graphich.agency\/it\/wp-json\/wp\/v2\/posts\/14958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acoredu.graphich.agency\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acoredu.graphich.agency\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acoredu.graphich.agency\/it\/wp-json\/wp\/v2\/users\/4703"}],"replies":[{"embeddable":true,"href":"https:\/\/acoredu.graphich.agency\/it\/wp-json\/wp\/v2\/comments?post=14958"}],"version-history":[{"count":1,"href":"https:\/\/acoredu.graphich.agency\/it\/wp-json\/wp\/v2\/posts\/14958\/revisions"}],"predecessor-version":[{"id":14959,"href":"https:\/\/acoredu.graphich.agency\/it\/wp-json\/wp\/v2\/posts\/14958\/revisions\/14959"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acoredu.graphich.agency\/it\/wp-json\/wp\/v2\/media\/14785"}],"wp:attachment":[{"href":"https:\/\/acoredu.graphich.agency\/it\/wp-json\/wp\/v2\/media?parent=14958"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acoredu.graphich.agency\/it\/wp-json\/wp\/v2\/categories?post=14958"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acoredu.graphich.agency\/it\/wp-json\/wp\/v2\/tags?post=14958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}