{"id":10073,"date":"2020-12-02T22:16:41","date_gmt":"2020-12-03T03:16:41","guid":{"rendered":"https:\/\/acoredu.graphich.agency\/?p=10073"},"modified":"2020-12-02T22:23:10","modified_gmt":"2020-12-03T03:23:10","slug":"whats-new-in-msk-imaging-italian-december-2020","status":"publish","type":"post","link":"https:\/\/acoredu.graphich.agency\/it\/whats-new-in-msk-imaging-italian-december-2020\/","title":{"rendered":"What&#8217;s new in MSK Imaging (Italian) &#8211; December 2020"},"content":{"rendered":"<h5><span style=\"color: #3366ff;\"><strong>Superolateral Hoffa Fat Pad Edema and Patellofemoral Maltracking: Systematic Review and Meta-Analysis<\/strong><\/span><\/h5>\n<p>Kim JH, Lee SK.<\/p>\n<p>American Journal of Roentgenology. 2020 Jun 6:1-3.<\/p>\n<p><a href=\"https:\/\/www.ajronline.org\/doi\/abs\/10.2214\/AJR.19.22263\">https:\/\/www.ajronline.org\/doi\/abs\/10.2214\/AJR.19.22263<\/a><\/p>\n<p><strong>Background<\/strong>: l&#8217;edema superolaterale del cuscinetto adiposo di Hoffa (SHFP) \u00e8 un segno di una sindrome sottostante caratterizzata da dolore al ginocchio anteriore e dolorabilit\u00e0 nel polo inferiore della rotula in giovani adulti. \u00c8 causato dall&#8217;attrito tra il tendine rotuleo e il condilo femorale laterale, che porta a un\u2019alterazione edemigena nell&#8217;SHFP per reazione infiammatoria. La RM ha dimostrato un&#8217;eccellente capacit\u00e0 nel confermare questa diagnosi clinica mediante la dimostrazione di un aumento focale dell&#8217;intensit\u00e0 del segnale in immagini con soppressione del grasso T2 pesate o pesate in densit\u00e0 protonica del SHFP tra il tendine rotuleo e il condilo femorale laterale.<\/p>\n<p><strong>Domande<\/strong>: l&#8217;edema del SHFP \u00e8 ben noto per essere associato a maltracking e malallineamento rotuleo. La domanda \u00e8 se i pazienti con edema del SHFP siano pi\u00f9 sintomatici rispetto a quelli senza, avendo entrambi i gruppi altri parametri associati al maltracking. Quali parametri di imaging del maltracking femoro-rotuleo sono associati all&#8217;edema superolaterale del cuscinetto adiposo di Hoffa (SHFP)?<\/p>\n<p><strong>Design<\/strong>: revisione sistematica e meta-analisi<\/p>\n<p><strong>Criteri di inclusione<\/strong>: gli studi sono stati inclusi se soddisfacevano i criteri di confronto dei pazienti con e senza edema SHFP e di valutazione dei parametri di maltracking femoro-rotuleo in RM.<\/p>\n<p><strong>Criteri di esclusione<\/strong>: gli studi sono stati esclusi se si trattava di case report o serie di casi, articoli di revisione, linee guida, lettere all&#8217;editore, revisioni sistematiche o meta-analisi o abstracts di conferenze. Sono stati anche esclusi se non riportavano chiaramente i parametri di maltracking femoro-rotuleo in RM.<\/p>\n<p><strong>Metodo<\/strong>: \u00e8 stata eseguita una ricerca sistematica nei database MEDLINE, Embase e Cochrane Library per identificare gli studi che valutano la relazione tra edema SHFP e maltracking femoro-rotuleo. I parametri per la valutazione del maltracking femoro-rotuleo in RM sono stati rivisti per ogni studio. Due revisori hanno eseguito la selezione degli studi, la valutazione metodologica della qualit\u00e0 e l&#8217;estrazione dei dati.<\/p>\n<p><strong>Risultati principali<\/strong>: nove studi erano eleggibili per l&#8217;inclusione nel presente studio. Dai suddetti studi inclusi, sono stati analizzati nove parametri che valutano il maltracking femoro-rotuleo: angolo femoro-rotuleo laterale, inclinazione rotulea, lateralizzazione rotulea, profondit\u00e0 trocleare, profondit\u00e0 del solco, angolo del solco, inclinazione trocleare laterale, distanza tra la tuberosit\u00e0 tibiale e il solco trocleare e il rapporto Insall-Salvati. I pazienti con edema SHFP avevano una maggiore inclinazione rotulea, una maggiore lateralizzazione rotulea, una maggiore distanza tra la tuberosit\u00e0 tibiale e il solco trocleare e un rapporto Insall-Salvati pi\u00f9 elevato rispetto ai pazienti senza edema SHFP.<\/p>\n<p><strong>Conclusione<\/strong>: i parametri di imaging del maltracking femoro-rotuleo, come una rotula spostata lateralmente, una maggiore distanza TTTG e la rotula alta, sono correlati all&#8217;edema SHFP.<\/p>\n<p><strong>Commento<\/strong>: l&#8217;edema SHFP \u00e8 un reperto anatomico patologico e si osserva nel sito di conflitto femoro-rotuleo superolaterale. Tuttavia, \u00e8 difficile valutare la correlazione con il dolore o la mobilit\u00e0 ridotta. Congratulazioni per il bel lavoro nel riassumere l&#8217;associazione dell&#8217;edema SHFP con le misure di malallineamento femoro-rotuleo.<\/p>\n<p><strong>Messaggio da ricordare<\/strong>: Il dolore al ginocchio anteriore \u00e8 uno scenario di presentazione comune, ma impegnativo. Una delle cause principali \u00e8 il maltracking rotuleo. L&#8217;edema del cuscinetto adiposo superolaterale \u00e8 un indicatore secondario di maltracking. I fattori su cui concentrarsi sono:<\/p>\n<ul>\n<li>Rotula spostata lateralmente<\/li>\n<li>Maggiore distanza TT TG<\/li>\n<li>Rotula alta<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h5><span style=\"color: #3366ff;\"><strong>Quantitative Variable Assessment of Patellar Instability: An MRI-Based Study<\/strong><\/span><\/h5>\n<p>Friedman MV, Hillen TJ, Misra S, Hildebolt CF, Rubin DA.<\/p>\n<p>American Journal of Roentgenology. 2020 Sep 9:1-8.<\/p>\n<p><a href=\"https:\/\/www.ajronline.org\/doi\/abs\/10.2214\/AJR.19.22556\">https:\/\/www.ajronline.org\/doi\/abs\/10.2214\/AJR.19.22556<\/a><\/p>\n<p><strong>Background<\/strong>: la displasia trocleare, la lateralizzazione della tuberosit\u00e0 tibiale e la posizione alta della rotula sono stati identificati come i fattori pi\u00f9 importanti che predispongono i pazienti all&#8217;instabilit\u00e0 rotulea. La valutazione accurata e la caratterizzazione di questi diversi fattori aiutano a guidare la gestione del paziente, con la displasia trocleare considerata come uno dei fattori anatomici pi\u00f9 importanti.<\/p>\n<p><strong>Domande<\/strong>: i tre parametri RM per l&#8217;instabilit\u00e0 rotulea &#8211; TT-PCL, TT-TG e displasia trocleare &#8211; possono essere misurati in modo affidabile e riproducibile? Possono misurare la predisposizione anatomica all&#8217;instabilit\u00e0 rotulea individualmente o in combinazione con gli altri parametri?<\/p>\n<p><strong>Design<\/strong>: studio retrospettivo.<\/p>\n<p><strong>Partecipanti<\/strong>: la popolazione dello studio era composta da 43 donne e 57 uomini (et\u00e0 media, 21,7 anni; range, 13-50 anni) che hanno ricevuto una diagnosi clinica e RM di un evento di lussazione rotulea in un singolo centro dal 2013 al 2015.<\/p>\n<p><strong>Criteri di inclusione<\/strong>: pazienti che hanno ricevuto una diagnosi sia clinica che RM di un evento di lussazione rotulea. L&#8217;esame clinico ha rivelato risultati positivi al test dell\u2019apprensione, un&#8217;eccessiva traslazione del quadrante rotuleo, versamento articolare e una mancanza di risultati positivi dell&#8217;esame del crociato e meniscale.<\/p>\n<p><strong>Criteri di esclusione<\/strong>: storia di un evento di instabilit\u00e0 rotulea, precedente intervento chirurgico al ginocchio o lesione concomitante del legamento crociato o collaterale al momento dell&#8217;evento di lussazione rotulea con conseguente instabilit\u00e0 articolare che potrebbe influenzare le misurazioni desiderate.<\/p>\n<p><strong>Metodi<\/strong>: 100 pazienti con diagnosi di lesione da lussazione rotulea e 100 pazienti di controllo di pari et\u00e0 e sesso sono stati esaminati utilizzando la RM. Sono state misurate la distanza tra il tubercolo tibiale e il legamento crociato posteriore (TT-PCL), la distanza tra il tubercolo tibiale e il solco trocleare (TT-TG) e la profondit\u00e0 TG (displasia trocleare) da tre radiologi con formazione in radiologia muscoloscheletrica, in maniera indipendente. Il coefficiente di correlazione intraclasse (ICC) \u00e8 stato utilizzato per valutare l&#8217;affidabilit\u00e0 intra-osservatore e inter-osservatore. I parametri in entrambi i gruppi sono stati testati per l&#8217;interdipendenza l&#8217;uno dall&#8217;altro e sono stati confrontati per la prevalenza e l&#8217;associazione con instabilit\u00e0 rotulea.<\/p>\n<p><strong>Risultati principali<\/strong>: tutti e tre i parametri hanno mostrato un&#8217;affidabilit\u00e0 intra-osservatore e inter-osservatore quasi perfetta ed erano significativamente pi\u00f9 comuni nel gruppo di instabilit\u00e0 rotulea. La displasia trocleare aveva la pi\u00f9 alta associazione con l&#8217;instabilit\u00e0 rotulea, sia come parametro unico che in combinazione a coppie con un TT-TG anormale. I cut-off ottimali per TT-TG e TT-PCL normali erano rispettivamente di 15,00 mm o meno e di 21,30 mm o meno. La soglia di cut-off normale ottimale per la valutazione della displasia trocleare attraverso la profondit\u00e0 trocleare era di 4,95 mm o pi\u00f9.<\/p>\n<p><strong>Conclusione<\/strong>: le misurazioni di TT-PCL, TT-TG e displasia trocleare possono essere valutate in modo affidabile in RM con un&#8217;affidabilit\u00e0 intra e inter-osservatore quasi perfetta. Le normali soglie di cut-off sia di TT-TG (\u2264 15,00 mm) che di TT-PCL (\u2264 21,30 mm) in RM possono essere abbassate. Lo studio ha confermato 5 mm o pi\u00f9 come normale soglia di cut-off durante la valutazione della displasia trocleare attraverso la profondit\u00e0 trocleare. Infine, la prevalenza di lateralizzazione TT e displasia trocleare \u00e8 significativamente pi\u00f9 alta nella popolazione con instabilit\u00e0 rotulea e la displasia trocleare \u00e8 il fattore pi\u00f9 importante nello sviluppo dell&#8217;instabilit\u00e0 rotulea.<\/p>\n<p><strong>Commento<\/strong>: ottimo lavoro! Congratulazioni. Gli studi osservazionali o retrospettivi non possono tuttavia essere utilizzati per dimostrare il nesso di causalit\u00e0. L&#8217;associazione sarebbe un termine migliore. Si spera che i chirurghi prestino maggiore attenzione alla trocleoplastica nel contesto del disallineamento \/ maltracking femoro-rotuleo, una procedura meno comunemente eseguita in Nord America.<\/p>\n<p><strong>Messaggio da ricordare<\/strong>:<\/p>\n<ul>\n<li>I pazienti con instabilit\u00e0 rotulea sono preoccupati all&#8217;esame clinico, quando si mobilita la rotula.<\/li>\n<li>La displasia trocleare \u00e8 la causa principale dell&#8217;instabilit\u00e0 rotulea.<\/li>\n<li>E\u2019 utile guardare la profondit\u00e0 trocleare come indicatore di displasia.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h5><span style=\"color: #3366ff;\"><strong>Use of Advanced Imaging for Radiographically Occult Hip Fracture in Elderly Patients: A Systematic Review and Meta-Analysis<\/strong><\/span><\/h5>\n<p>Haj-Mirzaian A, Eng J, Khorasani R, Raja AS, Levin AS, Smith SE, Johnson PT, Demehri S.<\/p>\n<p>Radiology. 2020 Jul 7:192167.<\/p>\n<p><a href=\"https:\/\/pubs.rsna.org\/doi\/abs\/10.1148\/radiol.2020192167\">https:\/\/pubs.rsna.org\/doi\/abs\/10.1148\/radiol.2020192167<\/a><\/p>\n<p><strong>Background<\/strong>: il tasso complessivo di fratture dell&#8217;anca non identificate sulle radiografie ma che richiedono un intervento chirurgico (cio\u00e8 fratture chirurgiche dell&#8217;anca) rimane poco chiaro nei pazienti anziani che si sospetta abbiano tali fratture sulla base dei risultati clinici. Le fratture chirurgiche dell&#8217;anca sono state definite come fratture che richiedevano un intervento chirurgico immediato e includevano fratture della testa del femore, del collo del femore, intertrocanteriche o sotto-trocanteriche. Inoltre, l&#8217;importanza dell&#8217;imaging avanzato in questi pazienti non \u00e8 stata valutata in modo completo.<\/p>\n<p><strong>Domande<\/strong>: qual \u00e8 la frequenza della frattura dell&#8217;anca radiograficamente occulta nei pazienti anziani?<\/p>\n<p>Esiste una sottopopolazione ad alto rischio?<\/p>\n<p>La TC e la scansione ossea sono efficaci quanto la RM nel rilevamento delle fratture occulte?<\/p>\n<p><strong>Design<\/strong>: meta-analisi.<\/p>\n<p><strong>Partecipanti<\/strong>: sono stati identificati trentacinque studi (2992 pazienti; et\u00e0 media 76,8 anni \u00b1 6,0 [deviazione standard]; 66% donne).<\/p>\n<p><strong>Criteri di inclusione<\/strong>: gli studi sono stati inclusi se i pazienti avevano un sospetto clinico di frattura dell&#8217;anca ma non c&#8217;era evidenza radiografica di frattura chirurgica dell&#8217;anca (inclusa l&#8217;assenza di qualsiasi frattura definita o solo la presenza di frattura isolata del grande trocantere [GT]).<\/p>\n<p><strong>Criteri di esclusione<\/strong>: studi che valutano pazienti senza sospetto clinico di avere frattura dell&#8217;anca, pubblicazioni non in inglese, casi clinici, serie di casi, revisione, opinione \/ editoriale, studio su animali<\/p>\n<p><strong>Metodi<\/strong>: \u00e8 stata eseguita una ricerca in letteratura per identificare gli studi osservazionali in lingua inglese pubblicati dall&#8217;inizio al 27 settembre 2018. Il tasso di frattura chirurgica dell&#8217;anca \u00e8 stato riportato in ogni studio in cui \u00e8 stata utilizzata la RM come standard di riferimento. Sono stati valutati il tasso aggregato di fratture occulte, le performance diagnostiche della TC e della scintigrafia ossea e la forza dell&#8217;evidenza (SOE).<\/p>\n<p><strong>Risultati principali<\/strong>:<\/p>\n<p>1) La frequenza delle fratture dell&#8217;anca radiograficamente occulte \u00e8 elevata (range, 39% \u201392%) nei pazienti di et\u00e0 compresa tra 56 e 82 anni che presentano sospetto clinico di frattura dell&#8217;anca.<\/p>\n<p>2) I pazienti hanno una maggiore probabilit\u00e0 di frattura dell&#8217;anca occulta se hanno evidenza radiografica di frattura isolata del grande trocantere (rischio relativo, 2.4), hanno almeno 80 anni (rischio relativo, 1.3), hanno rapporti radiografici equivoci (rischio relativo, 1.6), e una chiara storia di traumi recenti (rischio relativo, 1.5). 3) La TC e la scintigrafia ossea sono meno sensibili per le fratture occulte dell&#8217;anca (sensibilit\u00e0, 79% e 87% rispettivamente) rispetto alla RM.<\/p>\n<p><strong>Conclusione<\/strong>: i pazienti anziani con dolore acuto all&#8217;anca e risultati negativi o ambigui alla radiografia iniziale hanno un&#8217;alta frequenza di fratture occulte dell&#8217;anca. Pertanto, le prestazioni di imaging avanzato (preferibilmente RM) possono essere clinicamente appropriate in tutti questi pazienti.<\/p>\n<p><strong>Commento<\/strong>: Congratulazioni per la vostra pubblicazione. L&#8217;analisi dimostra l&#8217;utilit\u00e0 della RM nelle fratture dell&#8217;anca, un fatto ben noto. Tuttavia, si dovrebbe valutare la tecnologia pi\u00f9 recente &#8211; TC a strati sottili, DECT con mappa dell&#8217;edema del midollo osseo, ecc. &#8211; molto pi\u00f9 facile da fare in ER rispetto alla RM.<\/p>\n<p><strong>Messaggi da ricordare<\/strong>:<\/p>\n<ul>\n<li>La frattura occulta dell&#8217;anca sulle radiografie \u00e8 un problema comune con risultati catastrofici, se non individuata.<\/li>\n<li>Con un&#8217;anamnesi clinica appropriata negli anziani, non si deve esitare a eseguire l&#8217;imaging avanzato &#8211; RM, poich\u00e9 cambia chiaramente la gestione.<\/li>\n<li>Studio RM breve: le sequenze pelviche coronali STIR e coronali T1 sono adeguate per la valutazione.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h5><span style=\"color: #3366ff;\"><strong>Diagnostic Accuracy of Limited MRI Protocols for Detecting Radiographically Occult Hip Fractures: A Systematic Review and Meta-Analysis<\/strong><\/span><\/h5>\n<p>Wilson MP, Nobbee D, Murad MH, Dhillon S, McInnes MD, Katlariwala P, Low G.<\/p>\n<p>American Journal of Roentgenology. 2020:1-9.<\/p>\n<p><a href=\"https:\/\/www.ajronline.org\/doi\/full\/10.2214\/AJR.19.22676\">https:\/\/www.ajronline.org\/doi\/full\/10.2214\/AJR.19.22676<\/a><\/p>\n<p><strong>Background<\/strong>: L&#8217;obiettivo principale di questa revisione sistematica e meta-analisi era valutare l&#8217;accuratezza diagnostica di protocolli RM limitati per il rilevamento di fratture femorali prossimali radiograficamente occulte rispetto a un protocollo RM multiparametrico con o senza esito clinico come standard di riferimento. I principali obiettivi secondari includevano la valutazione dell&#8217;accuratezza diagnostica dei protocolli pesati in T1 su un solo piano, STIR, pesate in T1 e STIR e pesate in T2 per l&#8217;individuazione di fratture femorali prossimali radiograficamente occulte.<\/p>\n<p><strong>Domande<\/strong>: qual \u00e8 l&#8217;accuratezza diagnostica dei protocolli RM brevi per il rilevamento di fratture femorali prossimali radiograficamente occulte?<\/p>\n<p><strong>Design<\/strong>: revisione sistematica e meta-analisi.<\/p>\n<p><strong>Criteri di inclusione<\/strong>: sono stati valutati, con revisione del testo completo, tutti gli articoli originali che valutavano l&#8217;accuratezza diagnostica di un protocollo RM limitato per il rilevamento di fratture femorali prossimali radiograficamente occulte in pazienti con dolore acuto all&#8217;anca dopo un trauma minore rispetto a un protocollo RM multiparametrico con o senza esito clinico come standard di riferimento.<\/p>\n<p><strong>Criteri di esclusione<\/strong>: gli studi sono stati esclusi dall&#8217;analisi se sono stati valutati solo pazienti pediatrici di et\u00e0 inferiore a 18 anni, se sono stati inclusi meno di 10 pazienti, se \u00e8 stata utilizzata una popolazione di pazienti diversa dai pazienti con dolore acuto all&#8217;anca dopo un trauma, se sono state incluse fratture non radiograficamente occulte, se un protocollo RM limitato non era il test indice, se la risonanza magnetica multiparametrica non era lo standard di riferimento, o, ancora, se non erano disponibili informazioni sufficienti per ricostruire una tabella di contingenza 2 \u00d7 2 dopo un tentativo di corrispondenza per e-mail con l&#8217;autore o gli autori. Inoltre, sono stati esclusi articoli non originali, quali articoli di revisione, linee guida, documenti di consenso, lettere ed editoriali.<\/p>\n<p><strong>Metodo<\/strong>: sono stati inclusi nell&#8217;analisi articoli originali con 10 o pi\u00f9 pazienti che valutavano protocolli RM limitati per la diagnosi di fratture femorali prossimali radiograficamente occulte rispetto alla RM multiparametrica con o senza esito clinico come standard di riferimento. Pazienti, dati clinici, RM, e i parametri delle prestazioni sono stati acquisiti indipendentemente da due revisori. La meta-analisi \u00e8 stata eseguita utilizzando un modello di regressione a effetti misti bivariati.<\/p>\n<p><strong>Risultati principali<\/strong>: cinque studi sono stati inclusi nella meta-analisi.<\/p>\n<ol>\n<li>La sensibilit\u00e0 e la specificit\u00e0 riepilogativa aggregata e ponderata e l&#8217;area sotto la curva ROC riepilogativa per protocolli RM brevi per il rilevamento di fratture dell&#8217;anca radiograficamente occulte erano rispettivamente 99%, 99% e 1.<\/li>\n<li>I valori aggregati di sensibilit\u00e0 e specificit\u00e0 per una sequenza pesata in T1 su un solo piano, solo sequenza STIR, sequenze T1 pesata e STIR e solo sequenza pesata in T2 erano i seguenti: 97% e 100%, 99% e 99%, 100% e 99% e 86% e 97%, rispettivamente.<\/li>\n<li>La sensibilit\u00e0 era del 100% quando le immagini venivano acquisite solo su scanner 3-T e del 99% quando interpretate solo da radiologi certificati. Il tempo medio di scansione per i protocolli RM brevi era inferiore a 5 minuti.<\/li>\n<\/ol>\n<p><strong>Conclusione<\/strong>: i protocolli RM brevi possono essere utilizzati come standard di cura nei pazienti con una frattura dell&#8217;anca sospetta ma radiograficamente occulta. Un protocollo composto da sequenze coronale T1 pesate e STIR \u00e8 sensibile al 100%.<\/p>\n<p><strong>Commento<\/strong>: Grazie per il vostro lavoro. Il protocollo RM breve dovrebbe essere utilizzato pi\u00f9 frequentemente dal dipartimento di emergenza, quando si valutano i pazienti, in particolare i pazienti anziani con dolore acuto all&#8217;anca o quando non possono caricare peso sull\u2019arto, e le radiografie sono normali. L&#8217;analisi dimostra ancora una volta l&#8217;utilit\u00e0 della RM nelle fratture dell&#8217;anca, un fatto ben noto. Tuttavia, si dovrebbe valutare la tecnologia pi\u00f9 recente &#8211; TC a strati sottili, DECT con mappa dell&#8217;edema del midollo osseo, ecc. &#8211; molto pi\u00f9 facile da fare in pronto soccorso rispetto alla RM.<\/p>\n<p><strong>Messaggi da ricordare<\/strong>:<\/p>\n<ul>\n<li>La risonanza magnetica \u00e8 eccellente per diagnosticare la frattura occulta dell&#8217;anca.<\/li>\n<li>Una protocollo breve in RM che dura meno di 5 minuti pu\u00f2 diagnosticare la maggior parte delle fratture occulte.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h5><span style=\"color: #3366ff;\"><strong>Dual-Energy CT for Suspected Radiographically Negative Wrist Fractures: A Prospective Diagnostic Test Accuracy Study<\/strong><\/span><\/h5>\n<p>M\u00fcller FC, Gosvig KK, B\u00f8rgesen H, Gade JS, Brejneb\u00f8l M, Rodell A, N\u00e8mery M, Boesen M.<\/p>\n<p>Radiology. 2020 Jul 14:192701.<\/p>\n<p><a href=\"https:\/\/pubs.rsna.org\/doi\/abs\/10.1148\/radiol.2020192701\">https:\/\/pubs.rsna.org\/doi\/abs\/10.1148\/radiol.2020192701<\/a><\/p>\n<p><strong>Background<\/strong>: i pazienti con trauma al polso e reperti negativi alle radiografie spesso vengono sottoposti a ulteriori esami RM per valutare fratture radiograficamente occulte. La TC a doppia energia pu\u00f2 essere pi\u00f9 facilmente disponibile della RM in alcune circostanze. Lo scopo di questo studio \u00e8 valutare l&#8217;accuratezza diagnostica della TC a doppia energia nell&#8217;aiutare a rilevare l&#8217;edema del midollo osseo e la frattura nei pazienti con trauma del polso e sospetto clinico di frattura ma risultati negativi alle radiografie.<\/p>\n<p><strong>Domande<\/strong>: quanto \u00e8 efficace la TC a doppia energia nel rilevamento dell&#8217;edema del midollo osseo e delle fratture del polso in pazienti con sospetto clinico di frattura risultati negativi alle radiografie?<\/p>\n<p><strong>Design<\/strong>: studio prospettico.<\/p>\n<p><strong>Partecipanti<\/strong>: pazienti adulti sono stati arruolati in modo prospettico tra gennaio 2018 e novembre 2018. Nell&#8217;analisi sono state quindi incluse settecentocinquanta ossa di 50 polsi di 46 pazienti (quattro pazienti avevano traumi bilaterali).<\/p>\n<p><strong>Criteri di inclusione<\/strong>: adulti (\u226518 anni) con trauma al polso sottoposti a RM erano eleggibili se avevano una storia di trauma rilevante con esami radiografici risultati negativi o inconcludenti, ma con sospetto clinico di frattura. Erano eleggibili anche i partecipanti con fratture visibili che erano stati indirizzati alla RM con il sospetto di fratture aggiuntive non visibili sulle radiografie.<\/p>\n<p><strong>Criteri di esclusione<\/strong>: controindicazioni alla RM, gravidanza, intervento chirurgico precedente o impianti metallici al polso interessato o incapacit\u00e0 di sollevare il braccio sopra la testa.<\/p>\n<p><strong>Metodi<\/strong>: i polsi sono stati esaminati con TC a doppia energia e RM e le immagini sono state lette da quattro lettori, i quali erano all&#8217;oscuro delle informazioni cliniche. La presenza di edema del midollo osseo e frattura \u00e8 stata valutata singolarmente per ogni osso. Lo standard di riferimento per l&#8217;edema del midollo osseo era la lettura combinata delle scansioni RM. Lo standard di riferimento per la frattura era invece una lettura combinata di RM e scansioni TC a doppia energia. Un quinto radiologo ha arbitrato i risultati in caso di discrepanze. L&#8217;accuratezza del test diagnostico \u00e8 stata calcolata per lettore e per i lettori combinati utilizzando test binomiali esatti.<\/p>\n<p><strong>Risultati principali<\/strong>:<\/p>\n<p>1) Sia la RM che la TC a doppia energia avevano un&#8217;elevata sensibilit\u00e0 (80% vs 91%) e specificit\u00e0 (93% vs 87%) nell&#8217;aiutare a rilevare le fratture del polso radiograficamente occulte.<\/p>\n<p>2) La TC a doppia energia aveva una sensibilit\u00e0 del 94% e una specificit\u00e0 del 65% nel rappresentare polsi con edema traumatico del midollo osseo in pazienti con fratture del polso radiograficamente occulte.<\/p>\n<p><strong>Conclusione<\/strong>: la TC a doppia energia aveva un&#8217;elevata sensibilit\u00e0 e una moderata specificit\u00e0 nel rilevamento dell&#8217;edema midollare del polso. La TC a doppia energia aveva un&#8217;elevata sensibilit\u00e0 e specificit\u00e0 nel rappresentare le fratture del polso in pazienti con sospette fratture del polso e risultati negativi alle radiografie.<\/p>\n<p><strong>Commento<\/strong>: grazie per la vostra pubblicazione. Nella letteratura DECT mancano studi pi\u00f9 ampi sulle fratture degli arti. Anche il confronto tra DECT e MRI \u00e8 eccellente. Nella nostra esperienza, quando il paziente viene ingessato, l&#8217;edema del midollo osseo per qualche motivo non \u00e8 visibile. Ci\u00f2 riduce la sensibilit\u00e0 di DECT.<\/p>\n<p><strong>Messaggi da portare a casa<\/strong>:<\/p>\n<ul>\n<li>La TC a doppia energia pu\u00f2 aiutare nell&#8217;identificazione dell&#8217;edema osseo.<\/li>\n<li>La disponibilit\u00e0 di DECT \u00e8 in aumento nei pronto soccorsi ed \u00e8 una soluzione rapida per il rilevamento di lesioni occulte del polso e per promuovere un trattamento appropriato.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h5><span style=\"color: #3366ff;\"><strong>Predicting Bone Marrow Edema and Fracture Age in Vertebral Fragility Fractures Using MDCT<\/strong><\/span><\/h5>\n<p>Chang MY, Lee SH, Ha JW, Park Y, Zhang HY, Lee SH.<\/p>\n<p>American Journal of Roentgenology. 2020 Oct;215(4):970-7.<\/p>\n<p><a href=\"https:\/\/www.ajronline.org\/doi\/abs\/10.2214\/AJR.19.22606\">https:\/\/www.ajronline.org\/doi\/abs\/10.2214\/AJR.19.22606<\/a><\/p>\n<p><strong>Background<\/strong>: una linea di frattura corticale o trabecolare senza destrutturazione ossea, sclerosi vertebrale diffusa e alterazione diffusa dei tessuti molli paravertebrali sono caratteristiche TC note delle VCF (fratture vertebrali da compressione) acute benigne, sebbene studi precedenti si siano concentrati principalmente sulla differenziazione tra VCF benigne e maligne piuttosto che sulla presenza o assenza di edema del midollo osseo (BME). Le indicazioni radiografiche di fratture acute (insorgenza &lt;2 mesi) da compressione sono la presenza di un difetto a gradino, la presenza di un&#8217;emorragia a carico dei \u00a0tessuti molli e una banda bianca lineare di addensamento. Queste caratteristiche radiografiche possono essere valutate anche su immagini TC.<\/p>\n<p><strong>Domande<\/strong>: In merito alle fratture da fragilit\u00e0 vertebrale, possono le caratteristiche evidenziate in TC essere un fattore predittivo dell&#8217;edema del midollo osseo visualizzato in RM e dell&#8217;et\u00e0 della frattura.<\/p>\n<p><strong>Design<\/strong>: studio retrospettivo.<\/p>\n<p><strong>Partecipanti<\/strong>: Sono stati incluse retrospettivamente un totale di 189 fratture toracolombari da compressione in 103 pazienti (14 uomini, 89 donne; et\u00e0 media, 76 anni) evidenziate con TC e RM della colonna vertebrale.<\/p>\n<p><strong>Criteri di inclusione<\/strong>: sono state ricercate le cartelle dei pazienti con codici diagnostici di frattura toracolombare da compressione, ma non di neoplasia, per trovare fratture benigne da compressione da fragilit\u00e0. Sono stati reclutati pazienti che erano stati sottoposti sia a TC che a RM della colonna vertebrale entro 7 giorni.<\/p>\n<p><strong>Criteri di esclusione<\/strong>: sono stati esclusi i pazienti che avevano una frattura da compressione derivante da traumi ad alta energia (incidenti automobilistici e cadute da un&#8217;altezza superiore alla statura del paziente), infezione, un precedente intervento chirurgico che ha ostacolato la corretta analisi del cambiamento del segnale nel midollo osseo per artefatti metallici, immagini di scarsa qualit\u00e0 e compressione patologica da tumore benigno (emangioma).<\/p>\n<p><strong>Metodi<\/strong>: La presenza e l&#8217;estensione di BME sono state valutate alla RM per discernere tra fratture con e senza BME. Il gruppo con BME \u00e8 stato quindi classificato per l&#8217;analisi dei sottogruppi in fratture con BME esteso (che comprende il 50% o pi\u00f9 del corpo vertebrale) e quelli con BME che comprendono meno del 50% del corpo vertebrale. Alla TC sono state analizzate cinque caratteristiche (presenza di linea di frattura corticale o della limitante somatica, presenza di linea di frattura trabecolare, presenza di banda di addensamento, variazione dell&#8217;attenuazione trabecolare e ampiezza dei cambiamenti dei tessuti molli paravertebrali).<\/p>\n<p><strong>Risultati principali<\/strong>: tutti e cinque i risultati riscontrati alla TC sono stati osservati prevalentemente nelle fratture con BME. L&#8217;elevata attenuazione trabecolare, la presenza di una linea di frattura corticale o della limitante e l\u2019ampiezza del coinvolgimento dei tessuti molli paravertebrali hanno mostrato un&#8217;eccellente indicazione diagnostica per le fratture con BME. Nel sottogruppo con BME esteso, l&#8217;ampiezza del coinvolgimento dei tessuti molli paravertebrali era significativamente maggiore, mentre la variazione dell&#8217;attenuazione trabecolare era inferiore rispetto a quelli con BME che comprendeva meno del 50% del corpo vertebrale. Quando era presente BME, l&#8217;et\u00e0 della frattura non era significativamente diversa tra i due sottogruppi e solo una maggiore elevazione dell&#8217;attenuazione trabecolare era predittiva di una frattura pi\u00f9 vecchia sulle analisi del modello lineare misto.<\/p>\n<p><strong>Conclusione<\/strong>: le caratteristiche della TC correlano accuratamente con la presenza e l&#8217;estensione di BME nelle fratture da fragilit\u00e0 vertebrale. L&#8217;aumento dell&#8217;attenuazione trabecolare \u00e8 stato l&#8217;unico fattore predittivo significativo dell&#8217;et\u00e0 della frattura.<\/p>\n<p><strong>Commento<\/strong>: grazie per la vostra pubblicazione. La sclerosi e l&#8217;aumento della densit\u00e0 sono state utilizzate per identificare maggiormente fratture subacute e croniche. Questo lavoro porta avanti questa conoscenza e migliora la nostra comprensione sull\u2019et\u00e0 delle fratture.<\/p>\n<p><strong>Messaggi da ricordare<\/strong>:<\/p>\n<ul>\n<li>L&#8217;et\u00e0 delle fratture vertebrali \u00e8 difficile da prevedere.<\/li>\n<li>Utilizzando l&#8217;edema, la sclerosi e la densit\u00e0 del midollo osseo, \u00e8 possibile migliorare la predizione dell&#8217;et\u00e0 della frattura vertebrale.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h5><span style=\"color: #3366ff;\"><strong>Quantitative Magnetic Resonance Imaging UTE-T2* Mapping of Tendon Healing After Arthroscopic Rotator Cuff Repair: A Longitudinal Study<\/strong><\/span><\/h5>\n<p>Xie Y, Liu S, Qu J, Wu P, Tao H, Chen S.<\/p>\n<p>The American Journal of Sports Medicine. 2020 Aug 19:0363546520946772.<\/p>\n<p><a href=\"https:\/\/journals.sagepub.com\/doi\/abs\/10.1177\/0363546520946772\">https:\/\/journals.sagepub.com\/doi\/abs\/10.1177\/0363546520946772<\/a><\/p>\n<p><strong>Background<\/strong>: La sequenza di mappatura ultrashort echo time\u2013T2* (UTE-T2*) viene acquisita utilizzando tempi di eco diversi in un range di tempo di eco da corto ad ultracorto, il che rende possibile rilevare l&#8217;ultrastruttura dettagliata e quantificare ulteriormente le strutture con T2 \/ T2 * brevi\u00a0 ad esempio, il tendine). La tecnica di mappatura UTE-T2 * \u00e8 stata applicata per esplorare l&#8217;alterazione biochimica dei tendini. Durante le fasi proliferative e di rimodellamento dei processi riparativi della cuffia dei rotatori, viene inizialmente prodotto tessuto cicatriziale collagene disorganizzato nel sito di guarigione. Successivamente, le fibre collagene iniziano a depositarsi, orientarsi e riorganizzarsi. I valori UTE-T2 * hanno dimostrato di essere sensibili a questi cambiamenti biochimici della matrice di collagene.<\/p>\n<p><strong>Domande<\/strong>: valutare e caratterizzare il processo di guarigione della cuffia dei rotatori, sulla base dei cambiamenti longitudinali dei valori UTE-T2 *, dei risultati clinici e dello stato di riparazione nei pazienti dopo la riparazione artroscopica della cuffia dei rotatori (ARCR).<\/p>\n<p><strong>Design<\/strong>: studio di coorte.<\/p>\n<p><strong>Partecipanti<\/strong>: una serie consecutiva di pazienti (n = 25) con lesione del tendine sovraspinato che dovevano essere sottoposti a ARCR unilaterale presso il dipartimento di medicina dello sport tra il 2015 e il 2017. Tutte le lesioni sono state confermate mediante artroscopia. Un gruppo di volontari della stessa et\u00e0 (n = 15) sono stati reclutati come controlli sani.<\/p>\n<p><strong>Criterio di inclusione<\/strong>: Gruppo ARCR<\/p>\n<p>&#8211; (1) Lesione del tendine sovraspinato da piccola a grande (da \u22651 cm a &lt;5 cm) secondo i criteri stabiliti da DeOrio e Cofield<\/p>\n<p>(2) Indice di massa corporea &lt;30 kg \/ m2; e<\/p>\n<p>(3) Durata dei sintomi prima dell&#8217;intervento chirurgico \u00a0&lt;12 mesi.<\/p>\n<p><strong>Criteri di esclusione<\/strong>:<\/p>\n<p>1) Degenerazione adiposa di 3\u00b0 o 4\u00b0 grado nei muscoli della RC secondo la classificazione Goutallier<\/p>\n<p>(2) Artrite gleno-omerale da moderata a grave; e<\/p>\n<p>(3) Malattia neuromuscolare, artrite reumatoide, traumi o altre malattie sistemiche (ad es., diabete, ipertensione), controindicazione alla RM, come la claustrofobia.<\/p>\n<p><strong>Metodi<\/strong>: I pazienti con ARCR (n = 25) sono stati sottoposti a RM quantitativa ed esami clinici con intervalli di tempo di follow-up seriali: 3, 6, 12 e 24 mesi dopo l&#8217;intervento. I controlli sani di pari et\u00e0 (n = 15) sono stati valutati a 3 e 12 mesi dall&#8217;arruolamento. I punteggi clinici includevano gli score Constant, American Shoulder and Elbow Surgeons e Fudan University Shoulder e la scala analogica visiva per il dolore. L&#8217;esame RM includeva il mapping UTE-T2 *. Le mappe UTE-T2 * sono state generate per i valori T2 * nel sito di guarigione. La classificazione Sugaya \u00e8 stata adottata per valutare lo stato di riparazione. Sono state condotte analisi longitudinali degli esiti clinici, modifiche UTE-T2 * e classificazione Sugaya.<\/p>\n<p><strong>Risultati<\/strong>:<\/p>\n<ol>\n<li>La percentuale di recidiva complessiva \u00e8 stata dell&#8217;8% (2\/25, tutti Sugaya tipo IV). Tutti i pazienti (compresi quelli con recidiva) hanno raggiunto risultati soddisfacenti a 12 mesi che sono durati fino a 24 mesi sulla base dei punteggi clinici.<\/li>\n<li>I valori medi di UTE-T2 * nel sito di guarigione hanno mostrato un aumento da 3 a 6 mesi (P = .03) e poi sono diminuiti a un livello simile a quello osservato nei tendini sani di pazienti della stessa et\u00e0 a 12 mesi (P =. 1).<\/li>\n<li>Non sono state trovate differenze significative tra i valori UTE-T2 * a 12 e 24 mesi (P = .6).<\/li>\n<li>I valori UTE-T2 * nel sito di guarigione variavano significativamente con lo stato di riparazione secondo la classificazione Sugaya (P &lt;.05). Inoltre, sono state osservate correlazioni significative tra punteggi clinici e valori UTE-T2 * a 6 mesi e 12 mesi.<\/li>\n<\/ol>\n<p><strong>Conclusione<\/strong>: questo studio ha rilevato una correlazione, legata alla guarigione, tra risultati clinici e valori quantitativi di UTE-T2 * che evidenzia il potenziale dell&#8217;utilizzo della mappatura UTE-T2 * per monitorare il processo di guarigione dei tendini in modo non invasivo. Inoltre, il tendine riparato era paragonabile ai controlli sani di pari et\u00e0 al follow-up a 12 mesi sulla base dei valori UTE-T2 *.<\/p>\n<p><strong>Commento<\/strong>: grazie per il vostro lavoro innovativo. L&#8217;utilit\u00e0 pratica potrebbe non esserci ancora in questa fase, ma aiuta la nostra comprensione nei cambiamenti legati alla guarigione con la riparazione dei tendini.<\/p>\n<p><strong>Messaggi da ricordare<\/strong>:<\/p>\n<ul>\n<li>Il ritorno all&#8217;attivit\u00e0 si basa attualmente sull\u2019esame clinico dopo guarigione di una lesione del tendine della cuffia dei rotatori<\/li>\n<li>Mezzi di valutazione oggettivi sono importanti.<\/li>\n<\/ul>\n<p>L\u2019UTE fornisce una strada per valutare il grado di guarigione. Ambito da osservare, le tecniche e l\u2019interpretazione sono ancora nelle prime fasi.<\/p>\n<p>&nbsp;<\/p>\n<h5><span style=\"color: #3366ff;\"><strong>Imaging of the degenerative spine using a sagittal T2-weighted DIXON turbo spin-echo sequence<\/strong><\/span><\/h5>\n<p>Sollmann N, M\u00f6nch S, Riederer I, Zimmer C, Baum T, Kirschke JS.<\/p>\n<p>European Journal of Radiology. 2020 Aug 4:109204.<\/p>\n<p><a href=\"https:\/\/www.sciencedirect.com\/science\/article\/abs\/pii\/S0720048X20303934\">https:\/\/www.sciencedirect.com\/science\/article\/abs\/pii\/S0720048X20303934<\/a><\/p>\n<p><strong>Background<\/strong>: Valutare le prestazioni diagnostiche di una sequenza DIXON turbo spin-echo (TSE) pesata in T2 sagittale e valutare se le immagini fat-only possano sostituire sequenze dedicate sagittali pesate in T1 per la risonanza magnetica (RM) della colonna vertebrale degenerativa.<\/p>\n<p><strong>Domande<\/strong>: Pu\u00f2 la sequenza DIXON pesata in T2 senza una sequenza pesata in T1 separata rilevare accuratamente i comuni cambiamenti degenerativi della colonna vertebrale?<\/p>\n<p><strong>Design<\/strong>: studio osservazionale trasversale retrospettivo.<\/p>\n<p><strong>Partecipanti<\/strong>: Sono stati inclusi 35 pazienti (56,5 \u00b1 19,8 anni, 62,9% maschi) con lombalgia (LBP) sottoposti a RM della colonna lombare con inclusa una sequenza DIXON sagittale pesata in T2 (tempo di acquisizione: 3:25 min) e una sequenza pesata in T1 (tempo di acquisizione: 3:03 min).<\/p>\n<p><strong>Criteri di inclusione<\/strong>: i pazienti sono stati inclusi solo nel caso in cui avessero a disposizione una DIXON sagittale pesata in T2 e sequenze pesate in T2 senza contrasto, che coprivano l&#8217;intera colonna lombare.<\/p>\n<p><strong>Criteri di esclusione<\/strong>:<\/p>\n<p>1) et\u00e0 inferiore a 18 anni, \u00a02) artefatti da movimento all\u2019imaging, 3) presenza di eventuali impianti nel campo di vista (FOV), \u00a04) precedente intervento chirurgico con impianti alla colonna lombare, 5) scoliosi lombare, 6 ) storia di una malattia congenita con alterazioni strutturali manifestate a livello della colonna lombare (ad es. spina bifida, sindrome del midollo ancorato), 7) diagnosi di una malattia ematopoietica e \u00a08) presenza di fratture vertebrali, lesioni ossee maligne o lesioni spondilodiscitiche.<\/p>\n<p><strong>Metodi<\/strong>: sono stati valutati da due lettori (R1 e R2) due layout di immagine (layout 1: immagini fat-only E water-only E immagini in-fase della sequenza DIXON; layout 2: immagini water-only E in-fase della sequenza DIXON E immagini pesate in T1) in merito a cambiamenti degenerativi, includendo la confidenza diagnostica (1 &#8211; bassa, 2 &#8211; intermedia e 3 &#8211; alta) e cambiamenti del segnale del midollo osseo vertebrale (BM). I risultati sono stati confrontati tra lettori e layout.<\/p>\n<p><strong>Risultati principali<\/strong>: non sono state osservate differenze nel numero di patologie rilevate a livello di segmento, n\u00e9 nel numero di segmenti affetti da cambiamenti degenerativi quando si confrontano le valutazioni del layout 1 e del layout 2 per ciascun lettore. La confidenza diagnostica era alta senza una differenza statisticamente significativa tra le letture di entrambi i layout.<\/p>\n<p><strong>Conclusioni<\/strong>: nei pazienti con LBP, la RM utilizzando una sequenza DIXON sagittale pesata in T2 e nessuna sequenza separata pesata in T1 potrebbe essere sufficiente per rilevare con precisione i comuni cambiamenti degenerativi della colonna lombare con elevata confidenza diagnostica. Risparmiare sequenze dedicate pesate in T1 pu\u00f2 ridurre notevolmente il tempo di scansione complessivo.<\/p>\n<p><strong>Commento<\/strong>: Grazie per il vostro lavoro. T2W Dixon \u00e8 una routine anche nella nostra pratica da molto tempo. Riduce il tempo di imaging e, come per la colonna vertebrale, T2 Dixon a tre piani pu\u00f2 sostituire tutte le sequenze di imaging fornendo la valutazione del midollo e la valutazione della patologia nella stessa impostazione.<\/p>\n<p><strong>Messaggi da ricordare<\/strong>:<\/p>\n<ul>\n<li>La valutazione del midollo \u00e8 una componente essenziale della RM MSK.<\/li>\n<li>Il tempo per una RM \u00e8 fondamentale.<\/li>\n<li>L&#8217;imaging Multipoint Dixon potrebbe fornire soluzioni per saltare l\u2019imaging pesato in T1.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h5><span style=\"color: #3366ff;\"><strong>Influence of Acromial Morphologic Characteristics and Acromioclavicular Arthrosis on the Effect of Platelet-Rich Plasma on Partial Tears of the Supraspinatus Tendon<\/strong><\/span><\/h5>\n<p>Bern\u00e1-Mestre JD, Fern\u00e1ndez C, Carbonell G, Garc\u00eda A, Garc\u00eda-Vidal JA, Mirapeix FM, Bern\u00e1-Serna JD.<\/p>\n<p>American Journal of Roentgenology. 2020 Oct;215(4):954-62.<\/p>\n<p><a href=\"https:\/\/www.ajronline.org\/doi\/abs\/10.2214\/AJR.19.22331\">https:\/\/www.ajronline.org\/doi\/abs\/10.2214\/AJR.19.22331<\/a><\/p>\n<p><strong>Background<\/strong>: l&#8217;uso di plasma autologo ricco di piastrine (PRP) \u00e8 diventato molto diffuso per il trattamento delle anomalie tendinee. \u00c8 importante che l&#8217;infiltrazione venga eseguita con guida ecografica (US) per localizzare la lesione del tendine, inserire la punta dell&#8217;ago e confermare in tempo reale che la lesione del tendine sia riempita correttamente con PRP. Nessuno studio precedente ha analizzato l&#8217;effetto dell&#8217;infiltrazione di PRP guidata dagli US sulla dimensione dei diversi tipi di lesione SST parziale (spessore parziale e totale) o sulla borsite subacromiale-subdeltoidea (SASD) associata alla lesione.<\/p>\n<p><strong>Domande<\/strong>: quali sono gli effetti a medio termine dell&#8217;infiltrazione ecoguidata di plasma ricco di piastrine sulle lesioni parziali del tendine sovraspinato? \u00a0Quali sono gli indicatori prognostici di esito sfavorevole?<\/p>\n<p><strong>Design<\/strong>: studio prospettico<\/p>\n<p><strong>Partecipanti<\/strong>: nell&#8217;analisi sono stati inclusi un totale di 128 pazienti (66 uomini, 62 donne; et\u00e0 media 48,3 anni; range, 20-59 anni)<\/p>\n<p><strong>Criteri di inclusione<\/strong>: et\u00e0 20-60 anni, lesione parziale della SST diagnosticata con RM e dolore alla spalla che dura da pi\u00f9 di 3 mesi.<\/p>\n<p><strong>Criteri di esclusione<\/strong>: storia di trauma, intervento chirurgico o instabilit\u00e0 della spalla; ingestione di farmaci antinfiammatori non steroidei (FANS) o oppiacei; precedente infiltrazione locale alla spalla; RM pi\u00f9 di 1 anno prima; lacerazione completa dell&#8217;SST o lacerazione parziale di 1,5 cm o superiore o situata nella giunzione miotendinea; lesioni tendinee o ossee associate; ed evidente artrosi gleno-omerale (restringimento articolare clinicamente significativo, coinvolgimento subcondrale o osteofiti maggiori di 2 mm) o artropatia infiammatoria o cristallina.<\/p>\n<p><strong>Metodi<\/strong>: per un periodo di 4 anni, sono stati reclutati consecutivamente pazienti con una lesione parziale della SST inferiore a 1,5 cm sottoposti a infiltrazione PRP ecoguidata (1 mL) per dolore alla spalla della durata di pi\u00f9 di 3 mesi. La RM \u00e8 stata utilizzata per analizzare il tipo di acromion e la presenza di artrosi acromioclavicolare (AC). I risultati primari (dimensione della lesione e borsite associata) e secondari (mobilit\u00e0 e dolore) sono stati raccolti a 3 mesi.<\/p>\n<p><strong>Risultati principali<\/strong>: A 3 mesi, l&#8217;evoluzione favorevole nella riparazione della lacerazione \u00e8 stata registrata nel 71,1% dei pazienti e la risoluzione della borsite nel 66,7%. I cambiamenti nella dimensione della lacerazione hanno avuto grandi ripercussioni sull\u2019effetto, cos\u00ec come il dolore e la mobilit\u00e0 della spalla. I predittori pi\u00f9 forti di evoluzione sfavorevole in merito alla lacerazione e alle borsiti erano l&#8217;acromion di tipo 3 e l&#8217;acromion di tipo 1 e 2 con artrosi AC.<\/p>\n<p><strong>Conclusione<\/strong>: con lacerazioni SST parziali isolate inferiori a 1,5 cm la presenza di un acromion di tipo 3 o di un&#8217;artrosi AC grave \u00e8 predittiva di risultati sfavorevoli, e l&#8217;acromioplastica deve essere presa in considerazione, mentre nei pazienti con acromion di tipo 1, 2 o 4 con o senza lieve artrosi AC, la terapia PRP dovrebbe essere considerata come una delle prime opzioni terapeutiche.<\/p>\n<p><strong>Commento<\/strong>: Grazie per il vostro lavoro. L&#8217;acromion di tipo 3 \u00e8 molto raro nella nostra esperienza e per lo pi\u00f9 si trova vicino all&#8217;articolazione AC e potrebbe rappresentare l&#8217;osteofita stesso. La mancanza di confronto con altri trattamenti, ad es. il semplice trattamento steroideo o la fisioterapia \u00e8 stato un problema importante negli studi PRP e le prove del suo effetto sulla riparazione della cuffia dei rotatori (principalmente riempimento fibroso) si sono rilevate deboli nel migliore dei casi.<\/p>\n<p><strong>Messaggi da ricordare<\/strong>:<\/p>\n<ul>\n<li>Il PRP \u00e8 un&#8217;opzione per il trattamento delle lesioni della cuffia dei rotatori a spessore parziale.<\/li>\n<li>Non sono disponibili prove solide per la valutazione dell\u2019outcome per tale trattamento.<\/li>\n<li>Possono verificarsi problemi meccanici a causa della forma dell&#8217;acromion durante l&#8217;iniezione guidata da ultrasuoni nelle lesioni della cuffia dei rotatori.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h5><span style=\"color: #3366ff;\"><strong>Optimal Choice of Ultrasound-Based Measurements for the Diagnosis of Ulnar Neuropathy at the Elbow: A Meta-Analysis of 1961 Examinations<\/strong><\/span><\/h5>\n<p>Haj-Mirzaian A, Hafezi-Nejad N, Grande FD, Endo Y, Nwawka OK, Miller TT, Carrino JA.<\/p>\n<p>American Journal of Roentgenology. 2020 Nov;215(5):1171-83.<\/p>\n<p><a href=\"https:\/\/www.ajronline.org\/doi\/abs\/10.2214\/AJR.19.22457\">https:\/\/www.ajronline.org\/doi\/abs\/10.2214\/AJR.19.22457<\/a><\/p>\n<p><strong>Background<\/strong>: la neuropatia ulnare del gomito (UNE) \u00e8 una delle pi\u00f9 comuni neuropatie da intrappolamento periferico. In generale, le prove suggeriscono che l\u2019ecografia (US) possa essere utilizzata accuratamente per la diagnosi. Tuttavia, gli studi precedenti sono molto eterogenei per quanto riguarda le tecniche di misurazione ecografica utilizzate e i valori di cut-off; vari parametri misurati (diametro, area della sezione trasversale [CSA], rapporto del nervo ulnare); posizione di misurazione (dalla met\u00e0 del braccio al polso); e grado di flessione del gomito durante la misurazione.<\/p>\n<p><strong>Domande<\/strong>: qual \u00e8 la tecnica di misurazione ecografica ottimale e il valore di cut off per la diagnosi di neuropatia ulnare del gomito?<\/p>\n<p><strong>Design<\/strong>: meta-analisi.<\/p>\n<p><strong>Partecipanti<\/strong>: sono stati inclusi 19 studi (esami del 1961).<\/p>\n<p><strong>Criteri di inclusione<\/strong>: studi che valutano l&#8217;accuratezza diagnostica dell\u2019ecografia nei pazienti con neuropatia ulnare al gomito prima di aprile 2019.<\/p>\n<p><strong>Metodi<\/strong>: \u00e8 stato eseguito un modello a effetti casuali per confrontare la sensibilit\u00e0, la specificit\u00e0 e l&#8217;odds ratio diagnostico (DOR) di diverse misurazioni ecografiche, inclusi il diametro e l&#8217;area della sezione trasversale (CSA) del nervo a livello dell&#8217;epicondilo mediale o dei livelli prossimale e distale, diametro massimo, CSA massimo dei nervi ed i relativi indici (nerve ratios). Sono state eseguite analisi di sensibilit\u00e0 e metaregressione per valutare l&#8217;impatto delle variabili cliniche e di quelle basate sull&#8217;imaging nel DOR dell\u2019ecografia.<\/p>\n<p><strong>Risultati principali<\/strong>: la misurazione della CSA del nervo ulnare a livello dell&#8217;epicondilo mediale con un valore di cut-off maggiore di 10\u201310,5 mm2 ha avuto una sensibilit\u00e0 maggiore rispetto ad altre tecniche. Gli indici nervosi (nerve ratios) avevano una specificit\u00e0 maggiore rispetto ad altre misurazioni; tuttavia, la definizione dei rapporti e dei valori limite variava tra gli studi. L&#8217;analisi ROC ha mostrato prestazioni diagnostiche pi\u00f9 elevate per la misurazione della CSA nell&#8217;epicondilo mediale. Il valore CSA medio era un predittore significativo del DOR degli US. Ogni CSA pi\u00f9 grande di 1 mm2 \u00e8 stato associato a un aumento del 36% del DOR. La performance diagnostica dell&#8217;ecografia \u00e8 stata la stessa in qualsiasi grado di flessione del gomito.<\/p>\n<p><strong>Conclusione<\/strong>: la misurazione del CSA (non del diametro) del nervo ulnare, la misurazione a livello dell&#8217;epicondilo mediale (non ai livelli prossimali o distali) e l&#8217;uso di un valore di cut-off di 10-10,5 mm2 \u00e8 raccomandato per la diagnosi di neuropatia ulnare. Le misurazioni ecografiche possono essere eseguite in qualsiasi grado di flessione del gomito. Il diametro massimo del nervo, il CSA massimo e gli indici nervosi (nerve ratios) non possono essere considerati metodi ottimali per la diagnosi di UNE.<\/p>\n<p><strong>Commento<\/strong>: Congratulazioni per la vostra pubblicazione. L&#8217;elettrofisiologia dei falsi negativi e la neuropatia subclinica in assenza di sintomi evidenti rappresentano i problemi principali rispetto a uno standard di riferimento per la neuropatia ulnare. Tuttavia, questo lavoro aiuta a stabilire l&#8217;utilit\u00e0 dell\u2019ecografia nella UNE. Secondo l&#8217;esperienza dell&#8217;autore, un altro ruolo importante dell\u2019ecografia \u00e8 nella valutazione dinamica delle sindromi da scatto del nervo ulnare e dei tricipiti, che \u00e8 difficile da valutare con la RM.<\/p>\n<p><strong>Messaggi da ricordare<\/strong>:<\/p>\n<ul>\n<li>L&#8217;area della sezione trasversale del nervo ulnare \u00e8 un indicatore di neuropatia ulnare.<\/li>\n<li>Misurare il nervo ulnare nell&#8217;epicondilo mediale.<\/li>\n<li>Il valore di cut-off dell&#8217;area della sezione trasversale di 10-10.5mm2 \u00e8 un buon indicatore di neuropatia ulnare.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>Translated by: Laura Alonzo and Federica Vernuccio<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"Superolateral Hoffa Fat Pad Edema and Patellofemoral Maltracking: Systematic Review and Meta-Analysis Kim JH, Lee [&hellip;]","protected":false},"author":3,"featured_media":7171,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[206],"tags":[],"class_list":["post-10073","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-categorizzato"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>What&#039;s new in MSK Imaging (Italian) - December 2020 - ACORE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acoredu.graphich.agency\/it\/whats-new-in-msk-imaging-italian-december-2020\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"What&#039;s new in MSK Imaging (Italian) - December 2020 - ACORE\" \/>\n<meta property=\"og:description\" content=\"Superolateral Hoffa Fat Pad Edema and Patellofemoral Maltracking: Systematic Review and Meta-Analysis Kim JH, Lee [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acoredu.graphich.agency\/it\/whats-new-in-msk-imaging-italian-december-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"ACORE\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-03T03:16:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-03T03:23:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/acoredu.graphich.agency\/wp-content\/uploads\/2020\/08\/roentgenogram-P6QYVBD-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1761\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Abdelrahman\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Abdelrahman\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"30 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/acoredu.graphich.agency\\\/it\\\/whats-new-in-msk-imaging-italian-december-2020\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acoredu.graphich.agency\\\/it\\\/whats-new-in-msk-imaging-italian-december-2020\\\/\"},\"author\":{\"name\":\"Abdelrahman\",\"@id\":\"https:\\\/\\\/acoredu.graphich.agency\\\/#\\\/schema\\\/person\\\/250dc55c88746051517f8c7530c1a982\"},\"headline\":\"What&#8217;s new in MSK Imaging (Italian) &#8211; December 2020\",\"datePublished\":\"2020-12-03T03:16:41+00:00\",\"dateModified\":\"2020-12-03T03:23:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/acoredu.graphich.agency\\\/it\\\/whats-new-in-msk-imaging-italian-december-2020\\\/\"},\"wordCount\":6136,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/acoredu.graphich.agency\\\/it\\\/whats-new-in-msk-imaging-italian-december-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/acoredu.graphich.agency\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/roentgenogram-P6QYVBD-scaled.jpg\",\"articleSection\":[\"Non categorizzato\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/acoredu.graphich.agency\\\/it\\\/whats-new-in-msk-imaging-italian-december-2020\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acoredu.graphich.agency\\\/it\\\/whats-new-in-msk-imaging-italian-december-2020\\\/\",\"url\":\"https:\\\/\\\/acoredu.graphich.agency\\\/it\\\/whats-new-in-msk-imaging-italian-december-2020\\\/\",\"name\":\"What's new in MSK Imaging (Italian) - December 2020 - ACORE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acoredu.graphich.agency\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/acoredu.graphich.agency\\\/it\\\/whats-new-in-msk-imaging-italian-december-2020\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/acoredu.graphich.agency\\\/it\\\/whats-new-in-msk-imaging-italian-december-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/acoredu.graphich.agency\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/roentgenogram-P6QYVBD-scaled.jpg\",\"datePublished\":\"2020-12-03T03:16:41+00:00\",\"dateModified\":\"2020-12-03T03:23:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/acoredu.graphich.agency\\\/#\\\/schema\\\/person\\\/250dc55c88746051517f8c7530c1a982\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acoredu.graphich.agency\\\/it\\\/whats-new-in-msk-imaging-italian-december-2020\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acoredu.graphich.agency\\\/it\\\/whats-new-in-msk-imaging-italian-december-2020\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/acoredu.graphich.agency\\\/it\\\/whats-new-in-msk-imaging-italian-december-2020\\\/#primaryimage\",\"url\":\"https:\\\/\\\/acoredu.graphich.agency\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/roentgenogram-P6QYVBD-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/acoredu.graphich.agency\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/roentgenogram-P6QYVBD-scaled.jpg\",\"width\":2560,\"height\":1761,\"caption\":\"X-ray of hand and foot on black background\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acoredu.graphich.agency\\\/it\\\/whats-new-in-msk-imaging-italian-december-2020\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acoredu.graphich.agency\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"What&#8217;s new in MSK Imaging (Italian) &#8211; December 2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acoredu.graphich.agency\\\/#website\",\"url\":\"https:\\\/\\\/acoredu.graphich.agency\\\/\",\"name\":\"ACORE\",\"description\":\"Radiology education for everyone, everywhere!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acoredu.graphich.agency\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/acoredu.graphich.agency\\\/#\\\/schema\\\/person\\\/250dc55c88746051517f8c7530c1a982\",\"name\":\"Abdelrahman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad7486277da081678ef5e7172d9abecba77465cd62bd4d7272d1141d0b9bca2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad7486277da081678ef5e7172d9abecba77465cd62bd4d7272d1141d0b9bca2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad7486277da081678ef5e7172d9abecba77465cd62bd4d7272d1141d0b9bca2?s=96&d=mm&r=g\",\"caption\":\"Abdelrahman\"},\"url\":\"https:\\\/\\\/acoredu.graphich.agency\\\/it\\\/author\\\/abdelrahman\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"What's new in MSK Imaging (Italian) - December 2020 - ACORE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acoredu.graphich.agency\/it\/whats-new-in-msk-imaging-italian-december-2020\/","og_locale":"it_IT","og_type":"article","og_title":"What's new in MSK Imaging (Italian) - December 2020 - ACORE","og_description":"Superolateral Hoffa Fat Pad Edema and Patellofemoral Maltracking: Systematic Review and Meta-Analysis Kim JH, Lee [&hellip;]","og_url":"https:\/\/acoredu.graphich.agency\/it\/whats-new-in-msk-imaging-italian-december-2020\/","og_site_name":"ACORE","article_published_time":"2020-12-03T03:16:41+00:00","article_modified_time":"2020-12-03T03:23:10+00:00","og_image":[{"width":2560,"height":1761,"url":"https:\/\/acoredu.graphich.agency\/wp-content\/uploads\/2020\/08\/roentgenogram-P6QYVBD-scaled.jpg","type":"image\/jpeg"}],"author":"Abdelrahman","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Abdelrahman","Tempo di lettura stimato":"30 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/acoredu.graphich.agency\/it\/whats-new-in-msk-imaging-italian-december-2020\/#article","isPartOf":{"@id":"https:\/\/acoredu.graphich.agency\/it\/whats-new-in-msk-imaging-italian-december-2020\/"},"author":{"name":"Abdelrahman","@id":"https:\/\/acoredu.graphich.agency\/#\/schema\/person\/250dc55c88746051517f8c7530c1a982"},"headline":"What&#8217;s new in MSK Imaging (Italian) &#8211; December 2020","datePublished":"2020-12-03T03:16:41+00:00","dateModified":"2020-12-03T03:23:10+00:00","mainEntityOfPage":{"@id":"https:\/\/acoredu.graphich.agency\/it\/whats-new-in-msk-imaging-italian-december-2020\/"},"wordCount":6136,"commentCount":0,"image":{"@id":"https:\/\/acoredu.graphich.agency\/it\/whats-new-in-msk-imaging-italian-december-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/acoredu.graphich.agency\/wp-content\/uploads\/2020\/08\/roentgenogram-P6QYVBD-scaled.jpg","articleSection":["Non categorizzato"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/acoredu.graphich.agency\/it\/whats-new-in-msk-imaging-italian-december-2020\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/acoredu.graphich.agency\/it\/whats-new-in-msk-imaging-italian-december-2020\/","url":"https:\/\/acoredu.graphich.agency\/it\/whats-new-in-msk-imaging-italian-december-2020\/","name":"What's new in MSK Imaging (Italian) - December 2020 - ACORE","isPartOf":{"@id":"https:\/\/acoredu.graphich.agency\/#website"},"primaryImageOfPage":{"@id":"https:\/\/acoredu.graphich.agency\/it\/whats-new-in-msk-imaging-italian-december-2020\/#primaryimage"},"image":{"@id":"https:\/\/acoredu.graphich.agency\/it\/whats-new-in-msk-imaging-italian-december-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/acoredu.graphich.agency\/wp-content\/uploads\/2020\/08\/roentgenogram-P6QYVBD-scaled.jpg","datePublished":"2020-12-03T03:16:41+00:00","dateModified":"2020-12-03T03:23:10+00:00","author":{"@id":"https:\/\/acoredu.graphich.agency\/#\/schema\/person\/250dc55c88746051517f8c7530c1a982"},"breadcrumb":{"@id":"https:\/\/acoredu.graphich.agency\/it\/whats-new-in-msk-imaging-italian-december-2020\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acoredu.graphich.agency\/it\/whats-new-in-msk-imaging-italian-december-2020\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/acoredu.graphich.agency\/it\/whats-new-in-msk-imaging-italian-december-2020\/#primaryimage","url":"https:\/\/acoredu.graphich.agency\/wp-content\/uploads\/2020\/08\/roentgenogram-P6QYVBD-scaled.jpg","contentUrl":"https:\/\/acoredu.graphich.agency\/wp-content\/uploads\/2020\/08\/roentgenogram-P6QYVBD-scaled.jpg","width":2560,"height":1761,"caption":"X-ray of hand and foot on black background"},{"@type":"BreadcrumbList","@id":"https:\/\/acoredu.graphich.agency\/it\/whats-new-in-msk-imaging-italian-december-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acoredu.graphich.agency\/"},{"@type":"ListItem","position":2,"name":"What&#8217;s new in MSK Imaging (Italian) &#8211; December 2020"}]},{"@type":"WebSite","@id":"https:\/\/acoredu.graphich.agency\/#website","url":"https:\/\/acoredu.graphich.agency\/","name":"ACORE","description":"Radiology education for everyone, everywhere!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acoredu.graphich.agency\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/acoredu.graphich.agency\/#\/schema\/person\/250dc55c88746051517f8c7530c1a982","name":"Abdelrahman","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2ad7486277da081678ef5e7172d9abecba77465cd62bd4d7272d1141d0b9bca2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2ad7486277da081678ef5e7172d9abecba77465cd62bd4d7272d1141d0b9bca2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2ad7486277da081678ef5e7172d9abecba77465cd62bd4d7272d1141d0b9bca2?s=96&d=mm&r=g","caption":"Abdelrahman"},"url":"https:\/\/acoredu.graphich.agency\/it\/author\/abdelrahman\/"}]}},"_links":{"self":[{"href":"https:\/\/acoredu.graphich.agency\/it\/wp-json\/wp\/v2\/posts\/10073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acoredu.graphich.agency\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acoredu.graphich.agency\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acoredu.graphich.agency\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/acoredu.graphich.agency\/it\/wp-json\/wp\/v2\/comments?post=10073"}],"version-history":[{"count":3,"href":"https:\/\/acoredu.graphich.agency\/it\/wp-json\/wp\/v2\/posts\/10073\/revisions"}],"predecessor-version":[{"id":10076,"href":"https:\/\/acoredu.graphich.agency\/it\/wp-json\/wp\/v2\/posts\/10073\/revisions\/10076"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acoredu.graphich.agency\/it\/wp-json\/wp\/v2\/media\/7171"}],"wp:attachment":[{"href":"https:\/\/acoredu.graphich.agency\/it\/wp-json\/wp\/v2\/media?parent=10073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acoredu.graphich.agency\/it\/wp-json\/wp\/v2\/categories?post=10073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acoredu.graphich.agency\/it\/wp-json\/wp\/v2\/tags?post=10073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}